{"id":2519,"date":"2023-08-18T16:26:33","date_gmt":"2023-08-18T23:26:33","guid":{"rendered":"https:\/\/patriotfcu2.wpengine.com\/personal\/savings-money-market-accounts\/"},"modified":"2026-08-27T09:46:38","modified_gmt":"2026-08-27T13:46:38","slug":"cuentas-de-ahorro-del-mercado-monetario","status":"publish","type":"page","link":"https:\/\/www.patriotfcu.org\/es\/personal\/savings-money-market-accounts\/","title":{"rendered":"Cuentas de Ahorro &amp; Mercado Monetario"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__light co-flex_row__page-hero\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"co-page_hero light co-page_hero__has_image\" aria-label=\"Encabezado: Cuentas de ahorro y mercado monetario\">\n\t\t<div class=\"co-page_hero--inner\">\n\t\t\t<div class=\"prow gap:5 items-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-page_hero--img_wrap pcol-lg:5\">\n\t\t\t\t\t\t<div class=\"co-page_hero--wrapper\"><svg class=\"co-mask_image\" width=\"100%\" height=\"100%\" viewbox=\"0 0 800 800\" baseprofile=\"full\" version=\"1.2\"><defs><mask id=\"mask_6a97d0edadcf2\" maskunits=\"userSpaceOnUse\" maskcontentunits=\"userSpaceOnUse\" transform=\"scale(1)\"><image width=\"100%\" height=\"800\" xlink:href=\"https:\/\/www.patriotfcu.org\/wp-content\/themes\/patriotfcu-theme\/images\/hero_shape.svg\" alt=\"Image Mask Top Left\" \/><\/mask><\/defs><image class=\"image\" id=\"image_6a97d0edadd16\" mask=\"url(#mask_6a97d0edadcf2)\" width=\"100%\" height=\"800\" y=\"0\" x=\"0\" xlink:href=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Hero-Recovered-Recovered-12.jpg\" alt=\"couple looking at papers and calculator and smiling\" \/><\/svg><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"co-page_hero--text pcol-lg:7\">\n\t\t\t\t\t\t\t\t\t\t<h1 class=\"co-page_hero--title\">\n\t\t\t\t\t\tCuentas de Ahorro &amp; Mercado Monetario\t\t\t\t\t<\/h1>\n\t\t\t\t\t<p class=\"co-page_hero--tagline\">Obtenga mayores rendimientos y aumente sus ahorros.<\/p>\t\t\t\t\t\t<div class=\"co-page_hero--buttons\">\n\t\t\t\t\t\t\t<a data-trigger-id=\"5496\" class=\"modal-trigger co-page_hero--button\" href=\"#\">Abrir una nueva cuenta<\/a>\t<div class=\"co-overlay with-sidebar\" data-trigger-id=\"5496\">\n\t\t<div class=\"co-overlay--inner\">\n\t\t\t<div class=\"co-overlay--content text-component\">\n\t\t\t\t<div class=\"co-overlay--content_inner\">\n\t\t\t\t\t<h2 class=\"co-overlay--title\">Abrir una nueva cuenta\n\t\t\t\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<\/h2><p>Por favor seleccione una de las siguientes opciones:<\/p>\n\t\t\t\t\t\t<div class=\"co-overlay--cta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/onlinebanking.patriotfcu.org\/open-an-account\"  >Miembro actual<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/apply.patriotfcu.org\/apply.aspx?enc=Kw21Wblm1yxpjJabdoZaD-nApY8WNXWBtXXO-QDacmenEcOgxqGmwxj6QnF_S85MYoPrOFlldWZ_-sI_uIDMhNFGvx9jj8_cKm9AFkaDgnc&#038;_gl=1*8t98c0*_gcl_au*MjkxOTA3Nzk1LjE3MzI3MzM5NTY.*_ga*MTgzNTQ5MDg4MS4xNzMyNzMzOTUy*_ga_2BZ4WVY74J*MTczNzk4NDU4Ni4zNi4xLjE3MzgwMDQ0OTQuNTIuMC4w\"  >Nuevo miembro<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-overlay--sidebar text-component\">\n\t\t\t\t\t<h2>\u00bfPreguntas?<\/h2>\n<p>Hable con un representante local de servicios para miembros<\/p>\n<p>Ll\u00e1manos: <a href=\"tel: 18887779982\">888-777-9982<\/a><\/p>\n<p>Env\u00edenos un correo electr\u00f3nico: <a href=\"mailto:membersvc@patriotfcu.org\">membersvc@patriotfcu.org<\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<a class=\"co-page_hero--link\" href=\"https:\/\/appointments.patriotfcu.org\/service\" target=\"_blank\" >Agendar una cita de trabajo<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__page-intro\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-page_intro\">\n\t\t<h2 class=\"co-page_intro--title\">Disfrute de mayores rendimientos en cuentas de ahorro y del mercado monetario\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg><\/h2><div class=\"co-page_intro--desc\"><p>Patriot ofrece una variedad de opciones de ahorro. Ya sea que est\u00e9 ahorrando para su jubilaci\u00f3n, educaci\u00f3n, una casa o simplemente para un d\u00eda lluvioso, tenemos una cuenta de ahorros adecuada para usted en cualquier etapa de la vida.<\/p>\n<\/div>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__sticky-nav\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-sticky_nav_wrap is-active\" id=\"js-sticky_nav_wrap\">\n\t\t<nav\n\t\t\tclass=\"co-sticky_nav\"\n\t\t\tid=\"js-sticky_nav\"\n\t\t\taria-label=\"en la navegaci\u00f3n de anclaje de p\u00e1gina\"\n\t\t>\n\t\t\t<div class=\"co-sticky_nav--mobile\">\n\t\t\t\t<button\n\t\t\t\t\tclass=\"co-sticky_nav--toggle\"\n\t\t\t\t\tid=\"js-sticky_nav_toggle\"\n\t\t\t\t\taria-label=\"Abrir y cerrar men\u00fa de p\u00e1gina\"\n\t\t\t\t>Men\u00fa de p\u00e1gina<\/button>\n\t\t\t<\/div>\n\t\t\t<div\n\t\t\t\tclass=\"co-sticky_nav--row co-row\"\n\t\t\t\tid=\"js-sticky_nav_links\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#account\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\taria-label=\"Opciones de Cuentas\"\t\t\t\t\t>\n\t\t\t\t\t\tOpciones de Cuentas\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#rates\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\taria-label=\"Tarifas\"\t\t\t\t\t>\n\t\t\t\t\t\tTarifas\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#open\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\taria-label=\"Abierto ahora\"\t\t\t\t\t>\n\t\t\t\t\t\tAbre Ahora\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__columns\" id=\"benefits\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-columns\">\n\t\t\t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Tu camino hacia el crecimiento financiero comienza con Patriot\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2>\t<\/header>\n\t\t\t<div class=\"co-columns--row prow prow-md:2 prow-lg:3 co-columns--row__icons justify-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box co-columns--box_icon\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconMobilePhone\"\n\t\tviewbox=\"0 0 46 65\"\n\t\twidth=\"46\"\n\t\theight=\"65\"\n\t>\n\t\t<title>Tel\u00e9fono m\u00f3vil<\/title>\n\t\t\n\t\t<path data-name=\"Path 17236\" d=\"M44.123 53.332v-42h-43v42ZM19.606 27.994l3.169-6.365 3.125 6.388 7.032 1.047-5.113 4.944L29 41.02l-6.283-3.332-6.3 3.287 1.226-7-5.076-4.981Z\" fill=\"#ce1126\" class=\"accent\"\/>\n    <path data-name=\"Path 17237\" d=\"M25.7 5.819h-5.906a.631.631 0 1 0 0 1.262H25.7a.631.631 0 1 0 0-1.262\" fill=\"#fff\" class=\"white\"\/>\n    <path data-name=\"Path 17238\" d=\"M24.418 58.152h-3.34a.632.632 0 0 0 0 1.263h3.34a.632.632 0 1 0 0-1.263\" fill=\"#fff\" class=\"white\"\/>\n    <path data-name=\"Path 17239\" d=\"M16.621 5.819h-1a.631.631 0 1 0 0 1.262h1a.631.631 0 1 0 0-1.262\" fill=\"#fff\" class=\"white\"\/>\n    <path data-name=\"Path 17240\" d=\"m16.414 40.975 6.3-3.287L29 41.02l-1.178-7.012 5.113-4.944-7.035-1.047-3.125-6.386-3.169 6.363-7.039 1 5.073 4.981Z\" fill=\"#fff\" class=\"white\"\/>\n    <path data-name=\"Path 17241\" d=\"M38.009 0H7.492A7.5 7.5 0 0 0 0 7.494V57.16a7.5 7.5 0 0 0 7.492 7.493h30.516A7.5 7.5 0 0 0 45.5 57.16V7.494A7.5 7.5 0 0 0 38.009.002M19.794 5.819H25.7a.631.631 0 1 1 0 1.262h-5.9a.631.631 0 1 1 0-1.262m-4.174 0h1a.631.631 0 1 1 0 1.262h-1a.631.631 0 1 1 0-1.262m8.8 53.6h-3.34a.632.632 0 1 1 0-1.263h3.34a.632.632 0 0 1 0 1.263m19.705-6.083h-43v-42h43Z\" fill=\"#102164\"\/>\n\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Realice dep\u00f3sitos desde cualquier lugar<\/h3><div class=\"co-columns--box_desc\"><p>Disfrute de la comodidad de los dep\u00f3sitos m\u00f3viles las 24 horas, los 7 d\u00edas de la semana. Su camino seguro y sin complicaciones para hacer crecer sus fondos, en cualquier momento y en cualquier lugar.<\/p>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box co-columns--box_icon\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon Iconhandholdingcoin\"\n\t\tviewbox=\"0 0 60 62\"\n\t\twidth=\"60\"\n\t\theight=\"62\"\n\t>\n\t\t<title>Moneda de mano<\/title>\n\t\t\n\t\t<path data-name=\"Path 17425\" d=\"m1.113 61.51 10.594-9.71h22.7a.667.667 0 0 0 .343-.1l23.232-14.06c2-1.4 2.618-3.305 1.579-4.818-1.153-1.822-3.381-1.804-4.973-1.01L34.349 42.338H21.536l-.088-2.873 12.3-.219a3.614 3.614 0 0 0 2.1-6.354 3.534 3.534 0 0 0-2.581-.856l-10.547-.044a.658.658 0 0 0-.276.064.546.546 0 0 0-.278-.064l-7.566.087H9.926a.661.661 0 0 0-.487.213L.283 42.176a.663.663 0 0 0-.177.447L0 61.016a.667.667 0 0 0 .4.612\" fill=\"#022164\" class=\"primary\"\/>\n\t\t<path data-name=\"Path 17426\" d=\"M41.3 0a13 13 0 1 0 13 13 13 13 0 0 0-13-13\" fill=\"#ce1126\" class=\"accent\"\/>\n\t\t<path data-name=\"Path 17427\" d=\"M46.038 16.083a3.6 3.6 0 0 1-1.567 2.263 5.54 5.54 0 0 1-2.11.832v2.062h-2.305v-1.881a8.894 8.894 0 0 1-.435-.037 10.815 10.815 0 0 1-1.863-.35 6.929 6.929 0 0 1-1.281-.483l.647-2.79a8.208 8.208 0 0 0 3.56.89c1.03 0 1.758-.283 1.758-.93 0-.626-.606-1.012-2.1-1.477-2.2-.707-3.76-1.738-3.76-3.78a3.453 3.453 0 0 1 .645-2.033 4.118 4.118 0 0 1 1.905-1.418 6.02 6.02 0 0 1 1.029-.311V4.76h2.284v1.719a9.451 9.451 0 0 1 1.378.134 7.274 7.274 0 0 1 1.7.512l-.485 2.014-.162.676a7.344 7.344 0 0 0-3.053-.686c-1.194 0-1.558.423-1.558.869 0 .5.689.89 2.386 1.475 2.549.849 3.479 2 3.479 3.842a3.741 3.741 0 0 1-.085.768\" fill=\"#ce1126\" class=\"accent\"\/>\n\t\t<path data-name=\"Path 17428\" d=\"M42.644 11.473c-1.7-.586-2.386-.971-2.386-1.476 0-.445.364-.869 1.558-.869a7.33 7.33 0 0 1 3.052.687l.163-.676.485-2.013a7.13 7.13 0 0 0-1.7-.513 9.607 9.607 0 0 0-1.378-.134V4.76h-2.28v1.88a6.059 6.059 0 0 0-1.03.311 4.128 4.128 0 0 0-1.9 1.418 3.458 3.458 0 0 0-.644 2.032c0 2.043 1.556 3.074 3.76 3.781 1.5.465 2.1.85 2.1 1.476 0 .647-.728.93-1.759.93a8.23 8.23 0 0 1-3.56-.889l-.646 2.79a6.762 6.762 0 0 0 1.281.483 11.016 11.016 0 0 0 1.862.35c.145.015.29.028.436.037v1.881h2.305v-2.063a5.492 5.492 0 0 0 2.11-.832 3.606 3.606 0 0 0 1.567-2.262 3.741 3.741 0 0 0 .085-.768c0-1.84-.93-2.993-3.479-3.842\" fill=\"#fff\" class=\"white\"\/>\n\t\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Ahorrar Mas<\/h3><div class=\"co-columns--box_desc\"><p>Libere un mayor potencial de ahorro con nuestras tasas de dividendos competitivas. Deje que su dinero trabaje m\u00e1s y observe c\u00f3mo se disparan sus ahorros.<\/p>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box co-columns--box_icon\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconATM\"\n\t\tviewbox=\"0 0 74 62\"\n\t\twidth=\"74\"\n\t\theight=\"62\"\n\t>\n\t\t<title>Cajero autom\u00e1tico<\/title>\n\t\t\n\t\t<path data-name=\"Path 17259\" d=\"M74 0H0v47h22V23.884h-6.007a.808.808 0 1 1 0-1.615h41.464a.808.808 0 0 1 0 1.615H52V47h22ZM57.457 12.847H15.993a.808.808 0 1 1 0-1.615h41.464a.808.808 0 0 1 0 1.615\" fill=\"#022164\" class=\"primary\"\/>\n\t\t<path data-name=\"Path 17260\" d=\"M36.868 39.293c.019 0 .036.005.054.005l-.034-.055Z\" fill=\"#a8142a\"\/>\n\t\t<path data-name=\"Path 17261\" d=\"M38.506 44.285v-.022l-.014.013Z\" fill=\"#a8142a\"\/>\n\t\t<path data-name=\"Path 17262\" d=\"M36.889 28.742a4.953 4.953 0 0 0 4.942-4.858h-9.886a4.954 4.954 0 0 0 4.944 4.858\" fill=\"#ce1126\" class=\"accent\"\/>\n\t\t<path data-name=\"Path 17263\" d=\"M34.257 41.181a.1.1 0 0 0 .009-.029l-.035.005Z\" fill=\"#a8142a\"\/>\n\t\t<path data-name=\"Path 17264\" d=\"m39.485 41.222.048-.047-.066-.01c.007.018.012.038.018.057\" fill=\"#a8142a\"\/>\n\t\t<path data-name=\"Path 17265\" d=\"M51.789 23.884h-8.338a6.564 6.564 0 0 1-13.127 0H22V62h30V23.884ZM29.5 60.066h-5.9V53.1a6.254 6.254 0 0 1 5.9 6.967m20.674 0h-5.9a6.251 6.251 0 0 1 5.9-6.966Z\" fill=\"#ce1126\" class=\"accent\"\/>\n\t\t<path data-name=\"Path 17266\" d=\"M50.173 60.066V53.1a6.251 6.251 0 0 0-5.9 6.966Z\" fill=\"#fff\" class=\"white\"\/>\n\t\t<path data-name=\"Path 17267\" d=\"M29.5 60.066a6.254 6.254 0 0 0-5.9-6.966v6.967Z\" fill=\"#fff\" class=\"white\"\/>\n\t\t<path data-name=\"Path 17268\" d=\"M57.457 22.269H15.993a.808.808 0 1 0 0 1.615h14.332a6.564 6.564 0 0 0 13.126 0h14.006a.808.808 0 0 0 0-1.615m-20.568 6.473a4.954 4.954 0 0 1-4.944-4.858h9.886a4.953 4.953 0 0 1-4.942 4.858\" fill=\"#fff\" class=\"white\"\/>\n\t\t<path data-name=\"Path 17269\" d=\"M57.457 11.232H15.993a.808.808 0 1 0 0 1.615h41.464a.808.808 0 0 0 0-1.615\" fill=\"#fff\" class=\"white\"\/>\n\t\t<path data-name=\"Path 17270\" d=\"M37.977 40.482C36.5 39.973 35.9 39.639 35.9 39.2c0-.387.316-.756 1.354-.756a6.352 6.352 0 0 1 2.652.6l.562-2.337a6.826 6.826 0 0 0-2.671-.562v-1.496h-1.98v1.634c-2 .4-3.11 1.669-3.11 3.268 0 1.774 1.352 2.67 3.267 3.285 1.3.4 1.827.738 1.827 1.282 0 .562-.632.808-1.528.808a7.138 7.138 0 0 1-3.092-.773l-.562 2.425a8.382 8.382 0 0 0 3.109.755v1.634h2v-1.792C39.839 46.789 41 45.454 41 43.82c0-1.6-.809-2.6-3.023-3.338\" fill=\"#fff\" class=\"white\"\/>\n   \t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Dep\u00f3sitos Ilimitados<\/h3><div class=\"co-columns--box_desc\"><p>Libertad para depositar tantas veces como quieras, sin l\u00edmites. Tome el control y aumente sus ahorros sin problemas.<\/p>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__single-path-cta\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-sp_cta\">\n\t\t\t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Meet with Us\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2><div class=\"co-intro_text--intro\"><p>Need to meet with us in person? Schedule an appointment at your preferred branch and time.<\/p>\n<\/div>\t<\/header>\n<a class=\"co-sp_cta--button\" href=\"https:\/\/appointments.patriotfcu.org\/service\" target=\"_blank\" >Agendar una cita de trabajo<\/a>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__long-form-text\" id=\"account\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-long_form\">\n\t\t\t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Opciones de Cuentas\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2>\t<\/header>\n\t\t\t<div class=\"co-long_form--block prow items-start justify-center\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:7\">\n\t\t\t\t\t<h3 class=\"co-long_form--headline\" >Cuentas del Mercado Monetario<\/h3><div class=\"co-long_form--content\"><p>Obtenga una tasa de dividendo m\u00e1s alta que en una cuenta de ahorros est\u00e1ndar si tiene un saldo de al menos $2,500. Otros beneficios de la cuenta mercado monetario de Patriot incluyen:<\/p>\n<ul>\n<li>Saldo m\u00ednimo de $1,000 para abrir la cuenta<\/li>\n<li>Sin cargos<\/li>\n<li>Dep\u00f3sitos ilimitados<\/li>\n<li>Retiros ilimitados<\/li>\n<li>Capacidades de emisi\u00f3n de cheques<\/li>\n<li>La estructura de tasas escalonadas ofrece a los miembros con saldos m\u00e1s altos una mayor tasa de dividendos sobre los dep\u00f3sitos.<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-long_form--media pcol-md:5\">\n\t\t\t\t\t\t<div class=\"co-long_form--media_container\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"440\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered.jpg\" class=\"co-long_form--image\" alt=\"pareja mirando tableta y sonriendo\" srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered.jpg 600w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-540x396.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-16x12.jpg 16w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-396x290.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-75x55.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"co-long_form--block prow items-start justify-centerflex-row-reverse\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:7\">\n\t\t\t\t\t<h3 class=\"co-long_form--headline\" >Cuentas de Ahorro<\/h3><div class=\"co-long_form--content\"><p>Nuestra cuenta de ahorros b\u00e1sica solo requiere un dep\u00f3sito m\u00ednimo de $5, lo que le otorga la propiedad parcial de la cooperativa de cr\u00e9dito. \u00bfSolo busca una cuenta de ahorros? Esta cuenta tambi\u00e9n se puede abrir como una cuenta independiente.<\/p>\n<ul>\n<li>Bajo saldo m\u00ednimo de $5<\/li>\n<li>Dep\u00f3sitos ilimitados<\/li>\n<li>Retiros ilimitados<\/li>\n<li>El saldo de la cuenta se puede utilizar como protecci\u00f3n de transferencia de sobregiro para una cuenta de cheques<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-long_form--media pcol-md:5\">\n\t\t\t\t\t\t<div class=\"co-long_form--media_container\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"440\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-1.jpg\" class=\"co-long_form--image\" alt=\"mujer sentada en su sof\u00e1 usando su computadora y sonriendo\" srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-1.jpg 600w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-1-540x396.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-1-16x12.jpg 16w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-1-396x290.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-1-75x55.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"co-long_form--block prow items-start justify-center\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:7\">\n\t\t\t\t\t<h3 class=\"co-long_form--headline\" >Ahorrando para Ocasiones Especiales<\/h3><div class=\"co-long_form--content\"><ul>\n<li><strong>Club de Navidad<\/strong>\u00a0\u2013 Esta cuenta se paga a principios de octubre para ayudarle a ahorrar para las fiestas.<\/li>\n<li><strong>Club de Vacaciones<\/strong>\u00a0\u2013 Ahorre para las vacaciones (o cualquier cosa, en realidad) separando estos fondos de su cuenta de ahorros diaria. Utilice estos fondos cuando est\u00e9 listo.<\/li>\n<li><strong>Cuenta Secundaria<\/strong> \u2013 Separe los fondos para una ocasi\u00f3n o prop\u00f3sito especial de sus cuentas de ahorro diarias.<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-long_form--media pcol-md:5\">\n\t\t\t\t\t\t<div class=\"co-long_form--media_container\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"440\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-2.jpg\" class=\"co-long_form--image\" alt=\"familia de vacaciones en la playa\" srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-2.jpg 600w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-2-540x396.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-2-16x12.jpg 16w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-2-396x290.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Long-Form-1-Recovered-Recovered-Recovered-2-75x55.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__tabs\" id=\"rates\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-tabs\">\n\t\t\t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Tarifas de hoy\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2>\t<\/header>\n\t\t\t<div class=\"co-tabs--tabs js-tabs\">\n\t\t\t\t<nav class=\"co-tabs--nav\" aria-label=\"Tabs Navigation 6a97d0edbbea9\">\n\t\t\t\t\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"co-tabs--nav_toggle\t\t\t\t\t\t\t\tjs-tab_toggle\t\t\t\t\t\t\t\tjs-tab_toggle_large\"\n\t\t\t\t\t\t\tdata-tabtitle=\"savingsaccount\"\n\t\t\t\t\t\t\tdata-tabindex=\"0_savingsaccount\"\n\t\t\t\t\t\t\taria-label=\"Abrir cuenta de ahorros\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tCuenta de Ahorros\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"co-tabs--nav_toggle\t\t\t\t\t\t\t\tjs-tab_toggle\t\t\t\t\t\t\t\tjs-tab_toggle_large\"\n\t\t\t\t\t\t\tdata-tabtitle=\"moneymarketaccount\"\n\t\t\t\t\t\t\tdata-tabindex=\"1_moneymarketaccount\"\n\t\t\t\t\t\t\taria-label=\"Abrir cuenta del mercado monetario\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tCuentas del Mercado Monetario\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"co-tabs--nav_toggle\t\t\t\t\t\t\t\tjs-tab_toggle\t\t\t\t\t\t\t\tjs-tab_toggle_large\"\n\t\t\t\t\t\t\tdata-tabtitle=\"christmasclubshare\"\n\t\t\t\t\t\t\tdata-tabindex=\"2_christmasclubshare\"\n\t\t\t\t\t\t\taria-label=\"Abierto Club de Navidad Compartir\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tClub de Navidad\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"co-tabs--nav_toggle\t\t\t\t\t\t\t\tjs-tab_toggle\t\t\t\t\t\t\t\tjs-tab_toggle_large\"\n\t\t\t\t\t\t\tdata-tabtitle=\"vacationclubshare\"\n\t\t\t\t\t\t\tdata-tabindex=\"3_vacationclubshare\"\n\t\t\t\t\t\t\taria-label=\"Abierto Club Vacacional Compartir\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tClub de Vacaciones\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<\/nav>\n\n\t\t\t\t<div class=\"co-tabs--panels\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-tab js-tab co-tab__0\">\n\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\t\tclass=\"co-tab--toggle\t\t\t\t\t\t\t\t\tjs-tab_toggle\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"0_savingsaccount\"\n\t\t\t\t\t\t\t\taria-label=\"Abrir cuenta de ahorros con pesta\u00f1a m\u00f3vil\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\tCuenta de Ahorros\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<section\n\t\t\t\t\t\t\t\tclass=\"co-tab--content\t\t\t\t\t\t\t\t\tco-row\t\t\t\t\t\t\t\t\tjs-tab_content\"\n\t\t\t\t\t\t\t\taria-label=\"Contenido de la pesta\u00f1a para cuenta de ahorros\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"0_savingsaccount\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table_wrap co-rates_table_wrap__rates_list\">\n\t<table class=\"co-rates_table\">\n\t\t<caption class=\"co-rates_table_wrap--title\" id=\"sharesavingsprimarysharesecondaryshareescrowshareaccumulativerothtraditionalirashare\">\n\t\t\tAhorros en acciones (participaci\u00f3n primaria, participaci\u00f3n secundaria, participaci\u00f3n en dep\u00f3sito en garant\u00eda, participaci\u00f3n Roth acumulativa\/IRA tradicional)\t\t<\/caption>\n\t\t\t\t\t<thead>\n\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t\t<tr>\n\t\t\t\t\t<td class=\"co-rates_table--foot_cell\" colspan=\"2\">\n\t\t\t\t\t\t<p><sup>1<\/sup>APY = Rendimiento porcentual anual. Las tarifas son variables y est\u00e1n sujetas a cambios en cualquier momento.<br \/>\nTarifas vigentes al 27 de noviembre de 2024<br \/>\n<a href=\"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/\" class=\"co-button\">Aprende m\u00e1s<\/a><\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/tfoot>\n\t\t\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$5<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>0.20%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t\t<\/table>\n<\/div>\n\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-tab js-tab co-tab__1\">\n\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\t\tclass=\"co-tab--toggle\t\t\t\t\t\t\t\t\tjs-tab_toggle\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"1_moneymarketaccount\"\n\t\t\t\t\t\t\t\taria-label=\"Abrir cuenta de mercado monetario con pesta\u00f1a m\u00f3vil\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\tCuentas del Mercado Monetario\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<section\n\t\t\t\t\t\t\t\tclass=\"co-tab--content\t\t\t\t\t\t\t\t\tco-row\t\t\t\t\t\t\t\t\tjs-tab_content\"\n\t\t\t\t\t\t\t\taria-label=\"Contenido de la pesta\u00f1a para la cuenta del mercado monetario\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"1_moneymarketaccount\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table_wrap co-rates_table_wrap__rates_list\">\n\t<table class=\"co-rates_table\">\n\t\t<caption class=\"co-rates_table_wrap--title\" id=\"creditunioninsuredmoneymarketaccountcuimma\">\n\t\t\tCuenta del mercado monetario asegurada de la cooperativa de cr\u00e9dito (CUIMMA)\t\t<\/caption>\n\t\t\t\t\t<thead>\n\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t\t<tr>\n\t\t\t\t\t<td class=\"co-rates_table--foot_cell\" colspan=\"2\">\n\t\t\t\t\t\t<p><sup>1<\/sup>APY = Rendimiento porcentual anual. Las tarifas son variables y est\u00e1n sujetas a cambios en cualquier momento.<br \/>\nTarifas vigentes a partir del 1 de enero de 2026<br \/>\n<a href=\"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/\" class=\"co-button\">Aprende m\u00e1s<\/a><\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/tfoot>\n\t\t\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$2,500<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>1.00%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$10,000<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>1.10%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$25,000<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>1.25%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$100,000<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>1.55%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$250,000 <\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>1.75%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t\t<\/table>\n<\/div>\n\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-tab js-tab co-tab__2\">\n\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\t\tclass=\"co-tab--toggle\t\t\t\t\t\t\t\t\tjs-tab_toggle\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"2_christmasclubshare\"\n\t\t\t\t\t\t\t\taria-label=\"Abrir pesta\u00f1a m\u00f3vil Club de Navidad Compartir\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\tClub de Navidad\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<section\n\t\t\t\t\t\t\t\tclass=\"co-tab--content\t\t\t\t\t\t\t\t\tco-row\t\t\t\t\t\t\t\t\tjs-tab_content\"\n\t\t\t\t\t\t\t\taria-label=\"Contenido de la pesta\u00f1a Club de Navidad Compartir\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"2_christmasclubshare\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table_wrap co-rates_table_wrap__rates_list\">\n\t<table class=\"co-rates_table\">\n\t\t<caption class=\"co-rates_table_wrap--title\" id=\"christmasclubshare\">\n\t\t\tClub de Navidad\t\t<\/caption>\n\t\t\t\t\t<thead>\n\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>Desembolso<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t\t<tr>\n\t\t\t\t\t<td class=\"co-rates_table--foot_cell\" colspan=\"3\">\n\t\t\t\t\t\t<p><sup>1<\/sup>APY = Rendimiento porcentual anual. Las tarifas son variables y est\u00e1n sujetas a cambios en cualquier momento.<br \/>\nTarifas vigentes a partir del 2 de marzo de 2026<br \/>\n<a href=\"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/\" class=\"co-button\">Aprende m\u00e1s<\/a><\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/tfoot>\n\t\t\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$0<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Desembolso<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>1 de octubre<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>0.20%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t\t<\/table>\n<\/div>\n\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-tab js-tab co-tab__3\">\n\t\t\t\t\t\t\t<button\n\t\t\t\t\t\t\t\tclass=\"co-tab--toggle\t\t\t\t\t\t\t\t\tjs-tab_toggle\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"3_vacationclubshare\"\n\t\t\t\t\t\t\t\taria-label=\"Abrir pesta\u00f1a M\u00f3vil Vacation Club Compartir\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\tClub de Vacaciones\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<section\n\t\t\t\t\t\t\t\tclass=\"co-tab--content\t\t\t\t\t\t\t\t\tco-row\t\t\t\t\t\t\t\t\tjs-tab_content\"\n\t\t\t\t\t\t\t\taria-label=\"Contenido de la pesta\u00f1a Club Vacacional Compartir\"\n\t\t\t\t\t\t\t\tdata-tabindex=\"3_vacationclubshare\"\n\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table_wrap co-rates_table_wrap__rates_list\">\n\t<table class=\"co-rates_table\">\n\t\t<caption class=\"co-rates_table_wrap--title\" id=\"vacationclubshare\">\n\t\t\tClub de Vacaciones\t\t<\/caption>\n\t\t\t\t\t<thead>\n\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t\t<tr>\n\t\t\t\t\t<td class=\"co-rates_table--foot_cell\" colspan=\"2\">\n\t\t\t\t\t\t<p><sup>1<\/sup>APY = Rendimiento porcentual anual. Las tarifas son variables y est\u00e1n sujetas a cambios en cualquier momento.<br \/>\nTarifas vigentes al 27 de noviembre de 2024<br \/>\n<a href=\"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/\" class=\"co-button\">Aprende m\u00e1s<\/a><\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/tfoot>\n\t\t\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Saldo m\u00ednimo diario<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>$0<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>APY<sup>1<\/sup><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>0.20%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t\t<\/table>\n<\/div>\n\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__related-products\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-rel_prods center-narrow\">\n\t\t\t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Usted tambi\u00e9n puede estar interesado en\u2026\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2>\t<\/header>\n\t\t\t<div class=\"co-rel_prods--cols prow prow-md:2  justify-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-rel_prods--col\">\n\t\t\t\t\t\t<h3 class=\"co-rel_prods--col_title\">Servicios de protecci\u00f3n contra sobregiros<\/h3><div class=\"co-rel_prods--col_desc text-component\">La vida pasa y, a veces, eso significa que ocurren d\u00e9ficits financieros, por lo que ofrecemos varios servicios de protecci\u00f3n contra sobregiros para ayudarlo cuando lo necesite.<\/div><a class=\"co-rel_prods--col_cta\" href=\"https:\/\/www.patriotfcu.org\/es\/personal\/checking-accounts\/overdraft-services\/\" target=\"_blank\" aria-label=\"Lea m\u00e1s sobre los servicios de protecci\u00f3n contra sobregiros\">Aprende m\u00e1s<\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"co-rel_prods--col\">\n\t\t\t\t\t\t<h3 class=\"co-rel_prods--col_title\">Cuentas de Cheques<\/h3><div class=\"co-rel_prods--col_desc text-component\">Nuestras cuentas de cheques est\u00e1n dise\u00f1adas para hacer que su tiempo y dinero rindan m\u00e1s y ayudarle a aprovechar al m\u00e1ximo su experiencia bancaria.<\/div><a class=\"co-rel_prods--col_cta\" href=\"https:\/\/www.patriotfcu.org\/es\/personal\/checking-accounts\/\" target=\"_blank\" aria-label=\"Leer m\u00e1s sobre Cuentas Corrientes\">Aprende m\u00e1s<\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__back-to-top\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t<div class=\"co-back-to-top\">\t\n  <a class=\"co-back-to-top--link js-scroll_link\" href=\"#\" aria-label=\"\">\n\t\t<img\n\t\t\tclass=\"co-back-to-top--arrow\"\n\t\t\tsrc=\"https:\/\/www.patriotfcu.org\/wp-content\/themes\/patriotfcu-theme\/images\/circled-bordered-arrow.svg\"\n\t\t\talt=\"Bot\u00f3n Volver al principio\"\n\t\t\twidth=\"46\"\n\t\t\theight=\"46\"\n\t\t\tloading=\"lazy\"\n\t\t>\n\t  Volver arriba  <\/a>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__blog-feed\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t  <div class=\"co-blogFeed custom_blog related_post-wrapper\">\n    <div class=\"block-inner\">\n      \t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Explore nuestro blog para obtener consejos sobre dinero y m\u00e1s\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2><div class=\"co-intro_text--intro\"><p>Encuentre sugerencias financieras, consejos pr\u00e1cticos e historias de \u00e9xito financiero.<\/p>\n<\/div>\t<\/header>\n      <div class=\"co-blogFeed--row  justify-center\">\n      \t\t<div class=\"prow prow-md:2 prow-lg:3\">\n\t\t\t\t\t<article\n\t\t\t\tclass=\"co-blog_post  post-2519 page type-page status-publish hentry\"\t\t\t\taria-label=\"Publicaci\u00f3n de blog en el feed: En qu\u00e9 se diferencian las cooperativas de cr\u00e9dito de los bancos\"\n\t\t\t>\n\t\t\t\t<div>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"478\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-730x478.jpg\" class=\"co-blog_post--img\" alt=\"Familia de tres personas sonriendo en el auto\" srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-730x478.jpg 730w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-540x354.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-768x503.jpg 768w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-18x12.jpg 18w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-396x260.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-800x524.jpg 800w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7-75x49.jpg 75w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-7.jpg 1100w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div >\n\t\t\t\t\t<header\n\t\t\t\t\t\tclass=\"co-blog_post--header\"\n\t\t\t\t\t\taria-label=\"Encabezado de la publicaci\u00f3n del blog: En qu\u00e9 se diferencian las cooperativas de cr\u00e9dito de los bancos\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<h2 class=\"co-blog_post--title\">\n\t\t\t\t\t\t\t<a class=\"co-blog_post--title_link\" href=\"https:\/\/www.patriotfcu.org\/es\/blog\/how-credit-unions-differ-from-banks\/\">\n\t\t\t\t\t\t\t\tEn qu\u00e9 se diferencian las cooperativas de cr\u00e9dito de los bancos\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<\/header><!-- .entry_header -->\n\t\t\t\t\t<div class=\"co-blog_post--excerpt\">\n\t\t\t\t\t\tDesde fuera, las cooperativas de cr\u00e9dito parecen muy similares a los bancos. Ambos ofrecen productos y servicios financieros similares, desde cuentas corrientes y de ahorro hasta pr\u00e9stamos...\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.patriotfcu.org\/es\/blog\/how-credit-unions-differ-from-banks\/\"\n\t\t\t\t\t\t\t\tclass=\"co-read-more\"\n\t\t\t\t\t\t\t\taria-label=\"leer m\u00e1s sobre: En qu\u00e9 se diferencian las cooperativas de cr\u00e9dito de los bancos\"\n\t\t\t\t\t\t\t> Leer m\u00e1s<\/a>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div><!-- .entry_content -->\n\t\t\t\t\t<footer class=\"co-blog_post--footer\" aria-label=\"Pie de p\u00e1gina de la publicaci\u00f3n del blog: En qu\u00e9 se diferencian las cooperativas de cr\u00e9dito de los bancos\">\n\t\t\t\t\t\t\t\t\t\t\t<\/footer><!-- .entry_footer -->\n\t\t\t\t<\/div>\n\t\t\t<\/article><!-- #post-## -->\n\t\t\t\t\t<article\n\t\t\t\tclass=\"co-blog_post  post-2519 page type-page status-publish hentry\"\t\t\t\taria-label=\"Publicaci\u00f3n de blog en el feed: Aumente sus ahorros sin riesgo de mercado\"\n\t\t\t>\n\t\t\t\t<div>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"478\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-730x478.jpg\" class=\"co-blog_post--img\" alt=\"Pilas crecientes de monedas con plantas encima\" srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-730x478.jpg 730w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-540x354.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-768x503.jpg 768w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-18x12.jpg 18w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-396x260.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-800x524.jpg 800w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6-75x49.jpg 75w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-6.jpg 1100w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div >\n\t\t\t\t\t<header\n\t\t\t\t\t\tclass=\"co-blog_post--header\"\n\t\t\t\t\t\taria-label=\"Encabezado de la publicaci\u00f3n del blog: Aumente sus ahorros sin riesgo de mercado\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<h2 class=\"co-blog_post--title\">\n\t\t\t\t\t\t\t<a class=\"co-blog_post--title_link\" href=\"https:\/\/www.patriotfcu.org\/es\/blog\/boost-your-savings-without-market-risk\/\">\n\t\t\t\t\t\t\t\tAumente sus ahorros sin riesgo de mercado\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<\/header><!-- .entry_header -->\n\t\t\t\t\t<div class=\"co-blog_post--excerpt\">\n\t\t\t\t\t\tCuando se trata de invertir su dinero, hay una amplia gama de opciones disponibles. Estas oportunidades incluyen acciones, bonos, cuentas de ahorro tradicionales y bienes ra\u00edces,...\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.patriotfcu.org\/es\/blog\/boost-your-savings-without-market-risk\/\"\n\t\t\t\t\t\t\t\tclass=\"co-read-more\"\n\t\t\t\t\t\t\t\taria-label=\"leer m\u00e1s sobre: Aumente sus ahorros sin riesgo de mercado\"\n\t\t\t\t\t\t\t> Leer m\u00e1s<\/a>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div><!-- .entry_content -->\n\t\t\t\t\t<footer class=\"co-blog_post--footer\" aria-label=\"Pie de p\u00e1gina de la publicaci\u00f3n del blog: Aumente sus ahorros sin riesgo de mercado\">\n\t\t\t\t\t\t\t\t\t\t\t<\/footer><!-- .entry_footer -->\n\t\t\t\t<\/div>\n\t\t\t<\/article><!-- #post-## -->\n\t\t\t\t\t<article\n\t\t\t\tclass=\"co-blog_post  post-2519 page type-page status-publish hentry\"\t\t\t\taria-label=\"Publicaci\u00f3n de blog en el feed: Cancelar suscripci\u00f3n y guardar: terminar con sus suscripciones\"\n\t\t\t>\n\t\t\t\t<div>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"478\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-730x478.jpg\" class=\"co-blog_post--img\" alt=\"Mujer en el sof\u00e1 mirando las opciones de su tableta\" srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-730x478.jpg 730w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-540x354.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-768x503.jpg 768w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-18x12.jpg 18w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-396x260.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-800x524.jpg 800w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13-75x49.jpg 75w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-13.jpg 1100w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div >\n\t\t\t\t\t<header\n\t\t\t\t\t\tclass=\"co-blog_post--header\"\n\t\t\t\t\t\taria-label=\"Encabezado de la publicaci\u00f3n del blog: Cancelar suscripci\u00f3n y guardar: terminar con sus suscripciones\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<h2 class=\"co-blog_post--title\">\n\t\t\t\t\t\t\t<a class=\"co-blog_post--title_link\" href=\"https:\/\/www.patriotfcu.org\/es\/blog\/unsubscribe-save-breaking-up-with-your-subscriptions\/\">\n\t\t\t\t\t\t\t\tCancelar suscripci\u00f3n y ahorrar: terminar con sus suscripciones\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<\/header><!-- .entry_header -->\n\t\t\t\t\t<div class=\"co-blog_post--excerpt\">\n\t\t\t\t\t\tTodos los tenemos. Sabemos que cuestan una peque\u00f1a fortuna. Sin embargo, en lugar de cancelar suscripciones, nos encontramos suscribi\u00e9ndonos a a\u00fan m\u00e1s. Empresas en\u2026\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.patriotfcu.org\/es\/blog\/unsubscribe-save-breaking-up-with-your-subscriptions\/\"\n\t\t\t\t\t\t\t\tclass=\"co-read-more\"\n\t\t\t\t\t\t\t\taria-label=\"leer m\u00e1s sobre: Cancelar suscripci\u00f3n y guardar: terminar con sus suscripciones\"\n\t\t\t\t\t\t\t> Leer m\u00e1s<\/a>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div><!-- .entry_content -->\n\t\t\t\t\t<footer class=\"co-blog_post--footer\" aria-label=\"Pie de p\u00e1gina de la publicaci\u00f3n del blog: Cancelar suscripci\u00f3n y guardar: terminar con sus suscripciones\">\n\t\t\t\t\t\t\t\t\t\t\t<\/footer><!-- .entry_footer -->\n\t\t\t\t<\/div>\n\t\t\t<\/article><!-- #post-## -->\n\t\t\t<\/div>\n\t<div class=\"prow prow-md:12\">\n\t\t<a class=\"co-blog_post--see_all\" href=\"https:\/\/www.patriotfcu.org\/es\/blog\/\">Ver todas las publicaciones del blog<\/a>\n\t<\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__multi-path-cta\" id=\"open\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-mp_ctas\">\n\t\t\t<header class=\"co-intro_text\">\n\t\t<h2 class=\"co-intro_text--title\">Abra una cuenta de ahorros hoy\n\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/h2>\t<\/header>\n\t\t<div class=\"co-mp_ctas--list prow justify-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta pcol-lg:4\">\n\t\t\t\t\t<div class=\"co-mp_cta--title\">\n\t\t\t\t\t\tGet in Touch\t\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"co-mp_cta--link\" href=\"https:\/\/www.patriotfcu.org\/es\/contacto\/\"  >Cont\u00e1ctenos<\/a>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta pcol-lg:4\">\n\t\t\t\t\t<div class=\"co-mp_cta--title\">\n\t\t\t\t\t\tStart Online\t\t\t\t\t<\/div>\n\t\t\t\t\t<a data-trigger-id=\"5471\" class=\"modal-trigger co-mp_cta--link\" href=\"#\">Open An Account<\/a>\t<div class=\"co-overlay with-sidebar\" data-trigger-id=\"5471\">\n\t\t<div class=\"co-overlay--inner\">\n\t\t\t<div class=\"co-overlay--content text-component\">\n\t\t\t\t<div class=\"co-overlay--content_inner\">\n\t\t\t\t\t<h2 class=\"co-overlay--title\">Abrir una nueva cuenta\n\t\t\t\t\t\t\t<svg class=\"heading_shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"238.55799865722656\" height=\"14.876999855041504\" viewbox=\"0 0 238.558 14.877\">\n\t\t\t\t\t\t\t\t<path id=\"Path_16614\" data-name=\"Path 16614\" d=\"M5118.863,2995.027c15.19-6.542,69.982-8.38,118.5-2.822s90.372,10.077,113.638,2.822\" transform=\"translate(-5115.578 -2986.393)\" fill=\"none\" stroke=\"#ce1126\" stroke-linecap=\"round\" stroke-width=\"5\" class=\"title-shape\"><\/path>\n\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<\/h2><p>Por favor seleccione una de las siguientes opciones:<\/p>\n\t\t\t\t\t\t<div class=\"co-overlay--cta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/onlinebanking.patriotfcu.org\/open-an-account\"  >Miembro actual<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/apply.patriotfcu.org\/apply.aspx?enc=Kw21Wblm1yxpjJabdoZaD-nApY8WNXWBtXXO-QDacmenEcOgxqGmwxj6QnF_S85MYoPrOFlldWZ_-sI_uIDMhNFGvx9jj8_cKm9AFkaDgnc&#038;_gl=1*brn3ge*_gcl_aw*R0NMLjE3NzQ0NTYzNjQuQ2owS0NRandqNDdPQmhDbUFSSXNBRjV3VUVGc3owdHA0X2xGWFlCQk9vS0c2R2w2c2tQS2hiUW1PMEJIS3VvOWhERVFYRUdJTGp3Sk82VWFBcHZjRUFMd193Y0I.*_gcl_au*NTE4MTAwNDQ2LjE3NzczMDExNzg.*_ga*MTQ0NzAxMzczMC4xNzIyMjU4OTUz*_ga_2BZ4WVY74J*czE3ODA1ODA4OTgkbzQxOSRnMSR0MTc4MDU5MTg3OSRqMTMkbDAkaDA.\"  >Nuevo miembro<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-overlay--sidebar text-component\">\n\t\t\t\t\t<h2>\u00bfPreguntas?<\/h2>\n<p>Hable con un representante local de servicios para miembros<\/p>\n<p>Ll\u00e1manos: <a href=\"tel: 18887779982\">888-777-9982<\/a><\/p>\n<p>Env\u00edenos un correo electr\u00f3nico: <a href=\"mailto:membersvc@patriotfcu.org\">membersvc@patriotfcu.org<\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta pcol-lg:4\">\n\t\t\t\t\t<div class=\"co-mp_cta--title\">\n\t\t\t\t\t\tMeet With Us\t\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"co-mp_cta--link\" href=\"https:\/\/appointments.patriotfcu.org\/service\"  >Schedule Now<\/a>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-disclosures--icon svg-ncua\"\n\t\tviewbox=\"0 0 110 46\"\n\t\twidth=\"110\"\n\t\theight=\"46\"\n\t>\n\t\t<title>NCUA<\/title>\n\t\t\n    <path fill=\"#022164\" d=\"M100.684 43.343v-.3a1.549 1.549 0 0 0 .172.018c.166 0 .207-.088.248-.225l.043-.131-.623-1.637h.4l.434 1.229h.006l.414-1.229h.381l-.641 1.732c-.119.3-.2.563-.582.563a1.7 1.7 0 0 1-.252-.02Zm-7.24-.492h.363c.047.207.213.238.4.238a.37.37 0 0 0 .422-.416v-.254h-.006a.559.559 0 0 1-.492.289c-.523 0-.736-.391-.736-.865a.754.754 0 0 1 .742-.818.519.519 0 0 1 .486.268h.006v-.227h.361v1.561c0 .492-.291.734-.807.734-.335 0-.708-.125-.74-.51Zm.309-.973c0 .273.131.547.428.547.326 0 .445-.3.445-.57s-.131-.545-.445-.545-.429.297-.429.568Zm-32.768 1.139a.3.3 0 0 0 .207-.309h-.225v-.426h.445v.426a.509.509 0 0 1-.428.5Zm11.313-1.439a1.1 1.1 0 0 1 1.09-1.187.888.888 0 0 1 .967.771h-.385a.539.539 0 0 0-.582-.451c-.486 0-.693.434-.693.867s.207.865.693.865a.577.577 0 0 0 .635-.623h-.6v-.3h.965v1.191h-.254l-.061-.266a.816.816 0 0 1-.682.32 1.094 1.094 0 0 1-1.094-1.187Zm-3.854.379h.4c0 .35.262.486.576.486.35 0 .479-.172.479-.344a.267.267 0 0 0-.184-.279c-.16-.064-.367-.1-.676-.189-.391-.107-.5-.338-.5-.576 0-.449.416-.664.83-.664.469 0 .865.25.865.725h-.4c-.018-.291-.213-.4-.486-.4-.184 0-.414.072-.414.3 0 .16.105.25.266.291.035.012.539.143.658.178a.6.6 0 0 1 .439.574c0 .51-.451.713-.9.713-.522-.009-.942-.253-.954-.815Zm-3.066-.061v-1.451h.4v1.316c0 .307.018.658.533.658s.533-.352.533-.658v-1.316h.4v1.451a.934.934 0 0 1-1.863 0Zm-35.174 0v-1.451h.4v1.316c0 .307.018.658.533.658s.533-.352.533-.658v-1.316h.4v1.451a.933.933 0 0 1-1.861 0Zm-9.865-.318a1.1 1.1 0 0 1 1.09-1.187.881.881 0 0 1 .961.771h-.4a.55.55 0 0 0-.564-.451c-.486 0-.693.434-.693.867s.207.865.693.865a.586.586 0 0 0 .576-.594h.391a.931.931 0 0 1-.967.914 1.094 1.094 0 0 1-1.088-1.185Zm78.525.332a.789.789 0 0 1 .807-.885.662.662 0 0 1 .74.594h-.361a.348.348 0 0 0-.373-.309c-.189 0-.451.094-.451.6 0 .271.119.557.434.557a.386.386 0 0 0 .391-.373h.361a.7.7 0 0 1-.752.658.767.767 0 0 1-.797-.838Zm-3.594-.02a.8.8 0 1 1 1.572.09h-1.209a.437.437 0 0 0 .443.486.378.378 0 0 0 .4-.268h.344a.718.718 0 0 1-.742.553.779.779 0 0 1-.808-.861Zm.363-.146h.848a.436.436 0 0 0-.416-.434.431.431 0 0 0-.432.434Zm-9.891.146a.793.793 0 1 1 1.566.09h-1.2a.436.436 0 0 0 .438.486.385.385 0 0 0 .4-.268h.344a.724.724 0 0 1-.748.553.778.778 0 0 1-.8-.861Zm.363-.146h.842a.428.428 0 0 0-.41-.434.424.424 0 0 0-.432.434Zm-7.887.146a.793.793 0 1 1 1.566.09h-1.205a.434.434 0 0 0 .439.486.385.385 0 0 0 .4-.268h.34a.714.714 0 0 1-.742.553.775.775 0 0 1-.797-.861Zm.361-.146h.842a.421.421 0 1 0-.842 0Zm-3.895.146a.831.831 0 1 1 .83.861.794.794 0 0 1-.828-.861Zm.361 0c0 .285.148.576.469.576s.469-.291.469-.576-.143-.58-.469-.58-.467.297-.467.58Zm-11.3.664a.827.827 0 0 1-.57.2.5.5 0 0 1-.562-.475c0-.41.332-.48.635-.516.26-.043.492-.018.492-.232 0-.184-.191-.219-.338-.219-.2 0-.346.082-.363.26h-.361c.023-.42.379-.545.742-.545.326 0 .658.131.658.475v.848c0 .084.018.119.088.119a.539.539 0 0 0 .09-.006v.254a1.013 1.013 0 0 1-.232.037c-.141-.002-.247-.051-.276-.2Zm-.475-.568c-.154.023-.291.082-.291.273 0 .16.2.207.332.207.154 0 .4-.078.4-.309v-.268a1.316 1.316 0 0 1-.438.097Zm-6.113-.1a.828.828 0 1 1 .83.861.794.794 0 0 1-.827-.857Zm.361 0c0 .285.143.576.469.576s.463-.291.463-.576-.143-.58-.463-.58-.462.301-.462.584Zm-2.834.664a.822.822 0 0 1-.568.2c-.3 0-.562-.154-.562-.475 0-.41.326-.48.633-.516.262-.043.492-.018.492-.232 0-.184-.2-.219-.338-.219-.207 0-.35.082-.361.26h-.367c.029-.42.385-.545.746-.545.326 0 .658.131.658.475v.848c0 .084.023.119.09.119a.579.579 0 0 0 .088-.006v.254a1 1 0 0 1-.23.037c-.147.002-.246-.047-.277-.196Zm-.473-.568c-.154.023-.3.082-.3.273 0 .16.207.207.338.207.154 0 .4-.078.4-.309v-.268a1.337 1.337 0 0 1-.434.101Zm-4.482.2h.361c.023.213.178.285.373.285.137 0 .373-.029.367-.213s-.277-.215-.539-.273-.527-.154-.527-.486c0-.355.391-.469.688-.469.338 0 .641.137.688.5h-.379c-.035-.172-.178-.219-.332-.219-.107 0-.3.023-.3.166 0 .178.268.207.533.268s.533.152.533.479c0 .387-.4.529-.734.529-.414.003-.723-.177-.729-.568Zm-8.047-.3c0-.592.352-.854.713-.854a.639.639 0 0 1 .545.256h.006v-.836h.361v2.264h-.344v-.219h-.006a.546.546 0 0 1-.5.262c-.521-.003-.771-.384-.771-.877Zm.363.031c0 .277.141.557.455.557s.457-.291.457-.576c0-.367-.172-.58-.451-.58-.34 0-.457.3-.457.6Zm-7.068-.02a.831.831 0 1 1 .83.861.794.794 0 0 1-.827-.864Zm.361 0c0 .285.143.576.469.576s.469-.291.469-.576-.143-.58-.469-.58-.465.294-.465.577Zm-9.889-.012c0-.592.35-.854.713-.854a.647.647 0 0 1 .545.256h.006v-.836h.361v2.264h-.344v-.219h-.006a.551.551 0 0 1-.51.262c-.511-.002-.761-.383-.761-.876Zm.361.031c0 .277.137.557.451.557s.463-.291.463-.576c0-.367-.178-.58-.457-.58-.333.001-.453.301-.453.601Zm-2.127-.02a.792.792 0 1 1 1.564.09h-1.2a.433.433 0 0 0 .438.486.383.383 0 0 0 .4-.268h.344a.723.723 0 0 1-.748.553.776.776 0 0 1-.793-.863Zm.361-.146h.842a.421.421 0 1 0-.842 0Zm-6.012.811a.824.824 0 0 1-.57.2c-.295 0-.562-.154-.562-.475 0-.41.332-.48.635-.516.26-.043.492-.018.492-.232 0-.184-.2-.219-.338-.219-.207 0-.35.082-.361.26h-.363c.025-.42.381-.545.742-.545.326 0 .658.131.658.475v.848c0 .084.023.119.088.119a.563.563 0 0 0 .09-.006v.254a.949.949 0 0 1-.232.037c-.137-.005-.245-.054-.274-.203Zm-.475-.568c-.154.023-.291.082-.291.273 0 .16.2.207.332.207.16 0 .4-.078.4-.309v-.268a1.306 1.306 0 0 1-.435.094Zm-4.352-.1a.831.831 0 1 1 .83.861.794.794 0 0 1-.824-.86Zm.361 0c0 .285.148.576.469.576s.469-.291.469-.576-.143-.58-.469-.58-.463.298-.463.581Zm-2.828.664a.832.832 0 0 1-.568.2c-.3 0-.564-.154-.564-.475 0-.41.326-.48.635-.516.262-.043.492-.018.492-.232 0-.184-.2-.219-.344-.219-.2 0-.344.082-.361.26h-.361c.029-.42.385-.545.746-.545.32 0 .658.131.658.475v.848c0 .084.018.119.084.119a.607.607 0 0 0 .094-.006v.254a1.05 1.05 0 0 1-.23.037c-.144-.001-.246-.05-.275-.199Zm-.475-.568c-.154.023-.295.082-.295.273 0 .16.207.207.332.207.158 0 .408-.078.408-.309v-.268a1.338 1.338 0 0 1-.438.098Zm79.25.32v-.967h-.273v-.273h.273v-.49h.361v.49h.326v.273h-.326v.877c0 .148.012.227.172.227a.464.464 0 0 0 .154-.018v.283c-.076.006-.154.018-.236.018-.368.001-.439-.145-.444-.419Zm-34 0v-.967h-.271v-.273h.271v-.49h.361v.49h.332v.273h-.332v.877c0 .148.014.227.18.227a.469.469 0 0 0 .152-.018v.283c-.082.006-.158.018-.236.018-.374.001-.445-.145-.452-.419Zm-3.941 0v-.967h-.273v-.273h.273v-.49h.361v.49h.332v.273h-.332v.877c0 .148.018.227.178.227a.464.464 0 0 0 .154-.018v.283c-.084.006-.16.018-.238.018-.375.001-.445-.145-.451-.419Zm-23.234 0v-.967h-.273v-.273h.273v-.49h.367v.49h.326v.273h-.326v.877c0 .148.012.227.172.227a.469.469 0 0 0 .154-.018v.283c-.078.006-.154.018-.238.018-.375.001-.439-.145-.451-.419Zm-16.768 0v-.967h-.273v-.273h.273v-.49h.361v.49h.326v.273h-.326v.877c0 .148.012.227.178.227a.424.424 0 0 0 .148-.018v.283c-.076.006-.154.018-.23.018-.375.001-.447-.145-.453-.419Zm86.625.4v-1.031c-.012-.26-.107-.367-.326-.367a.4.4 0 0 0-.4.434v.965h-.357v-1.643h.34v.244l.006.006a.6.6 0 0 1 .516-.291.518.518 0 0 1 .58.559v1.125Zm-5.324 0-.207-.6h-.908l-.213.6h-.408l.871-2.264h.42l.873 2.264Zm-1.008-.9h.693l-.338-.973h-.012Zm-3.2.9v-1.031c-.006-.26-.107-.367-.32-.367a.4.4 0 0 0-.4.434v.965h-.363v-1.643h.344v.244l.006.006a.6.6 0 0 1 .512-.291.518.518 0 0 1 .58.559v1.125Zm-3.588 0v-.959c0-.262-.018-.439-.3-.439-.244 0-.344.16-.344.439v.959h-.363V41.65c0-.225-.07-.344-.289-.344a.379.379 0 0 0-.363.426v.973h-.361v-1.643h.344v.232h.012a.551.551 0 0 1 .5-.273.458.458 0 0 1 .457.273.6.6 0 0 1 .516-.273.482.482 0 0 1 .553.553v1.131Zm-2.762 0v-1.031c-.006-.26-.107-.367-.32-.367a.4.4 0 0 0-.4.434v.965h-.363v-1.643h.344v.244l.006.006a.6.6 0 0 1 .512-.291.518.518 0 0 1 .58.559v1.125Zm-2.254 0v-1.643h.338v.32h.006a.526.526 0 0 1 .48-.361c.084 0 .107.006.137.006v.35a1.367 1.367 0 0 0-.154-.012c-.248 0-.443.2-.443.559v.781Zm-2.982 0-.6-1.643h.4l.416 1.264h.006l.4-1.264h.373l-.586 1.643Zm-6.467 0v-.426h.443v.426Zm-2.936 0v-.426h.439v.426Zm-7.482 0v-1.031c-.006-.26-.105-.367-.32-.367a.4.4 0 0 0-.4.434v.965h-.361v-1.643h.344v.244l.006.006a.6.6 0 0 1 .51-.291.517.517 0 0 1 .582.559v1.125Zm-3.717 0v-1.643h.361v1.643Zm-3.949 0v-1.643h.338v.32h.006a.526.526 0 0 1 .48-.361c.084 0 .1.006.137.006v.35a1.439 1.439 0 0 0-.154-.012c-.248 0-.449.2-.449.559v.781Zm-3.461 0v-1.643h.361v1.643Zm-.754 0v-1.031c-.006-.26-.111-.367-.32-.367a.4.4 0 0 0-.4.434v.965h-.367v-1.643h.344v.244l.006.006a.6.6 0 0 1 .516-.291.518.518 0 0 1 .58.559v1.125Zm-1.838 0v-1.643h.361v1.643Zm-.752 0v-.959c0-.262-.012-.439-.3-.439-.244 0-.35.16-.35.439v.959h-.361V41.65c0-.225-.072-.344-.291-.344a.378.378 0 0 0-.355.426v.973h-.361v-1.643h.338v.232h.012a.553.553 0 0 1 .5-.273.46.46 0 0 1 .461.273.589.589 0 0 1 .518-.273c.344 0 .545.148.545.553v1.131Zm-4.549 0-.213-.6h-.906l-.215.6h-.408l.871-2.264h.422l.877 2.264Zm-1.008-.9h.689l-.34-.973h-.012Zm-2.145.9v-1.031c-.008-.26-.107-.367-.32-.367a.4.4 0 0 0-.4.434v.965h-.361v-1.643h.344v.244l.006.006a.6.6 0 0 1 .51-.291.519.519 0 0 1 .582.559v1.125Zm-3.719 0v-1.643h.361v1.643Zm-.752 0v-1.031c-.012-.26-.107-.367-.326-.367a.4.4 0 0 0-.393.434v.965h-.361v-1.643h.344v.244l.006.006a.587.587 0 0 1 .51-.291.519.519 0 0 1 .582.559v1.125Zm-6.072 0v-1.643h.363v1.643Zm-4.777 0v-1.643h.338v.32h.006a.528.528 0 0 1 .48-.361c.082 0 .105.006.137.006v.35a1.3 1.3 0 0 0-.154-.012c-.25 0-.445.2-.445.559v.781Zm-3.932 0v-2.264h.361v2.264Zm-2.52 0v-1.031c-.006-.26-.105-.367-.32-.367a.4.4 0 0 0-.4.434v.965h-.367v-1.643h.344v.244l.006.006a.6.6 0 0 1 .516-.291.518.518 0 0 1 .58.559v1.125Zm-3.717 0v-1.643h.361v1.643Zm-3.676 0-1.031-1.666h-.006v1.666h-.381v-2.264h.422l1.031 1.666h.006v-1.666h.379v2.264Zm47.619-1.926v-.338h.361v.338Zm-7.41 0v-.338h.361v.338Zm-2.592 0v-.338h.361v.338Zm-12.172 0v-.338h.361v.338Zm-6.824 0v-.338h.363v.338Zm-14.945 0v-.338h.361v.338Zm46.434-11.152c-1.387-1.523-1.678-2.7-1.678-5.17V14.314h4.287v10.145a5.464 5.464 0 0 0 .295 2.016 1.881 1.881 0 0 0 1.881 1.18 1.8 1.8 0 0 0 1.861-1.09 5.584 5.584 0 0 0 .271-2.105V14.314h4.287v10.145c0 2.811-.611 4.055-1.678 5.146a6.272 6.272 0 0 1-4.7 1.814 6.766 6.766 0 0 1-4.821-1.789ZM37.78 22.684a8.792 8.792 0 0 1 17.33-1.992h-4.485a4.348 4.348 0 0 0-4.061-2.928 4.646 4.646 0 0 0-4.494 4.9c0 2.537 1.725 4.986 4.518 4.986a4.483 4.483 0 0 0 4.037-2.834h4.494a8.609 8.609 0 0 1-8.484 6.6 8.729 8.729 0 0 1-8.85-8.729Zm-6.105 8.42-6.422-10.121.09 10.121h-4.1v-16.79h3.7l6.439 10.234-.09-10.234h4.1v16.791Zm51.354-.006-.795-2.426h-5.875l-.77 2.426h-4.648l6.646-16.785h3.693l6.443 16.785Zm-5.6-5.828h3.7l-1.887-5.852ZM22.706 9.743v-.3a1.541 1.541 0 0 0 .166.018c.172 0 .213-.088.254-.225l.043-.131-.623-1.631h.4l.428 1.223h.012l.414-1.223h.375l-.635 1.727c-.119.295-.207.563-.582.563a1.647 1.647 0 0 1-.249-.018Zm66.271-1.768a1.092 1.092 0 0 1 1.084-1.186.9.9 0 0 1 .973.777h-.391a.534.534 0 0 0-.582-.451c-.486 0-.687.428-.687.859s.2.865.688.865a.576.576 0 0 0 .635-.621h-.605v-.3h.967v1.2h-.254l-.061-.268a.827.827 0 0 1-.682.32 1.094 1.094 0 0 1-1.082-1.192Zm-10.27.381h.4c0 .35.254.484.574.484.35 0 .48-.172.48-.344a.269.269 0 0 0-.189-.277c-.16-.061-.367-.1-.676-.189a.575.575 0 0 1-.5-.576c0-.451.42-.664.83-.664.475 0 .871.25.871.725h-.4c-.02-.291-.215-.4-.492-.4-.186 0-.41.066-.41.291 0 .16.107.248.268.291.035.012.533.141.652.178a.6.6 0 0 1 .443.58c0 .5-.449.711-.9.711-.519.003-.933-.245-.947-.807Zm-10.416-.061V6.842h.4v1.322c0 .3.018.658.533.658s.535-.355.535-.658V6.842h.4v1.453a.933.933 0 0 1-1.861 0Zm34.125-.006a.8.8 0 1 1 1.572.09h-1.211a.443.443 0 0 0 .445.492.383.383 0 0 0 .4-.273h.346a.721.721 0 0 1-.742.557.782.782 0 0 1-.806-.862Zm.361-.143h.848a.424.424 0 1 0-.848 0Zm-7.885.143a.793.793 0 1 1 1.566.09h-1.205a.439.439 0 0 0 .439.492.385.385 0 0 0 .4-.273h.344a.724.724 0 0 1-.746.557.778.778 0 0 1-.794-.862Zm.361-.143h.842a.421.421 0 1 0-.842 0Zm-3.889.143a.828.828 0 1 1 .824.865.792.792 0 0 1-.819-.861Zm.361 0c0 .285.143.582.463.582s.469-.3.469-.582-.143-.58-.469-.58-.458.298-.458.584Zm-5.318.291h.363c.018.213.178.291.373.291.137 0 .373-.031.361-.221s-.273-.213-.533-.271-.527-.154-.527-.486c0-.355.385-.469.682-.469.338 0 .646.137.688.5h-.379c-.031-.172-.174-.219-.332-.219-.1 0-.3.023-.3.166 0 .178.266.207.533.266s.527.154.527.48c0 .391-.391.533-.734.533-.404.008-.711-.176-.717-.566Zm-1.754-.291a.792.792 0 1 1 1.564.09h-1.2a.439.439 0 0 0 .439.492.39.39 0 0 0 .4-.273h.338a.713.713 0 0 1-.74.557.778.778 0 0 1-.796-.862Zm.361-.143h.842a.428.428 0 0 0-.414-.437.424.424 0 0 0-.422.441Zm-2.068.807a.826.826 0 0 1-.564.2.5.5 0 0 1-.562-.48c0-.408.326-.479.629-.51.26-.047.492-.018.492-.23 0-.189-.191-.225-.338-.225-.2 0-.344.082-.363.26h-.361c.023-.42.387-.545.748-.545.32 0 .652.131.652.475v.848c0 .088.023.125.088.125a.275.275 0 0 0 .09-.012v.254a.967.967 0 0 1-.227.041c-.144.004-.25-.049-.279-.197Zm-.475-.568c-.154.023-.291.082-.291.271 0 .166.207.215.332.215.16 0 .408-.084.408-.314v-.268a1.352 1.352 0 0 1-.443.099Zm-6.582-.107c0-.592.35-.854.713-.854a.641.641 0 0 1 .545.256h.006v-.838h.361v2.266h-.344v-.219h-.006a.554.554 0 0 1-.51.266c-.509.003-.759-.382-.759-.874Zm.363.029c0 .285.141.564.449.564.326 0 .463-.3.463-.582 0-.361-.172-.58-.451-.58-.338.005-.455.305-.455.605Zm-2.129-.018a.795.795 0 1 1 1.57.09h-1.209a.439.439 0 0 0 .439.492.385.385 0 0 0 .4-.273h.344a.724.724 0 0 1-.746.557.777.777 0 0 1-.796-.862Zm.361-.143h.848a.424.424 0 1 0-.848 0Zm-8.947.143a.793.793 0 1 1 1.566.09h-1.2a.44.44 0 0 0 .438.492.389.389 0 0 0 .4-.273h.338a.717.717 0 0 1-.742.557.778.778 0 0 1-.794-.862Zm.363-.143h.842a.421.421 0 1 0-.842 0Zm-7.008.143a.831.831 0 1 1 .83.865.793.793 0 0 1-.824-.861Zm.361 0c0 .285.143.582.469.582s.467-.3.467-.582-.143-.58-.467-.58-.462.298-.462.584Zm-5.01-.012c0-.592.35-.854.711-.854a.632.632 0 0 1 .545.256h.006v-.838h.361v2.266h-.344v-.219h-.006a.547.547 0 0 1-.5.266c-.518.004-.766-.381-.766-.873Zm.361.029c0 .285.137.564.451.564s.461-.3.461-.582c0-.361-.172-.58-.455-.58-.331.006-.45.306-.45.606Zm-2.129-.018a.793.793 0 1 1 1.566.09h-1.205a.442.442 0 0 0 .439.492.385.385 0 0 0 .4-.273h.344a.724.724 0 0 1-.746.557.781.781 0 0 1-.791-.861Zm.361-.143h.848a.424.424 0 1 0-.848 0Zm-3.189.16a.787.787 0 0 1 .807-.883.662.662 0 0 1 .74.594h-.361a.344.344 0 0 0-.373-.309c-.189 0-.451.1-.451.6 0 .273.119.564.434.564a.39.39 0 0 0 .391-.375h.361a.707.707 0 0 1-.752.658.771.771 0 0 1-.789-.84Zm-2.822-.029c0-.592.35-.854.713-.854a.641.641 0 0 1 .545.256h.006V6.84h.361v2.266h-.344v-.219H48.1a.554.554 0 0 1-.51.266c-.508.005-.758-.38-.758-.872Zm.361.029c0 .285.137.564.451.564s.463-.3.463-.582c0-.361-.178-.58-.457-.58-.33.007-.45.307-.45.607Zm-2.834.646a.818.818 0 0 1-.562.2.5.5 0 0 1-.562-.48c0-.408.326-.479.629-.51.26-.047.5-.018.5-.23 0-.189-.2-.225-.344-.225-.2 0-.344.082-.361.26h-.361c.023-.42.385-.545.748-.545.318 0 .658.131.658.475v.848c0 .088.018.125.082.125a.275.275 0 0 0 .09-.012v.254a.967.967 0 0 1-.227.041.25.25 0 0 1-.283-.195Zm-.467-.568c-.16.023-.3.082-.3.271 0 .166.207.215.332.215.16 0 .408-.084.408-.314v-.268a1.348 1.348 0 0 1-.432.101Zm-5.822.568a.837.837 0 0 1-.57.2.5.5 0 0 1-.562-.48c0-.408.326-.479.629-.51.266-.047.492-.018.492-.23 0-.189-.189-.225-.338-.225-.2 0-.344.082-.361.26h-.363c.025-.42.387-.545.748-.545.32 0 .658.131.658.475v.848c0 .088.018.125.088.125a.256.256 0 0 0 .084-.012v.254a.949.949 0 0 1-.227.041c-.14.006-.247-.047-.271-.195Zm-.475-.568c-.16.023-.3.082-.3.271 0 .166.207.215.332.215.16 0 .41-.084.41-.314v-.268a1.338 1.338 0 0 1-.434.101Zm-5.8.123V7.469h.361v1c0 .291.119.4.314.4.3 0 .4-.2.4-.451v-.949h.361v1.643h-.355v-.23h-.006a.562.562 0 0 1-.469.271c-.419.005-.603-.208-.603-.639Zm-3.729-.219a.795.795 0 1 1 1.57.09H28.42a.442.442 0 0 0 .439.492.385.385 0 0 0 .4-.273h.344a.724.724 0 0 1-.746.557.781.781 0 0 1-.794-.86Zm.361-.143h.848a.424.424 0 1 0-.848 0Zm-7.275.736h-.006v.225h-.344V6.839h.363v.838h.006a.587.587 0 0 1 .484-.256.768.768 0 0 1 .771.871c0 .445-.225.859-.705.859a.583.583 0 0 1-.566-.265Zm0-.594c0 .332.166.582.463.582.326 0 .451-.3.451-.582s-.154-.58-.451-.58-.46.237-.46.587Zm-3.26-.012c0-.592.35-.854.711-.854a.632.632 0 0 1 .545.256h.008v-.838h.361v2.266h-.344v-.219h-.006a.554.554 0 0 1-.51.266c-.513.007-.761-.378-.761-.87Zm.361.029c0 .285.137.564.451.564s.463-.3.463-.582c0-.361-.172-.58-.457-.58-.334.009-.453.309-.453.609Zm-2.129-.018a.793.793 0 1 1 1.566.09h-1.2a.442.442 0 0 0 .443.492.386.386 0 0 0 .4-.273h.344a.725.725 0 0 1-.742.557.782.782 0 0 1-.803-.858Zm.363-.143h.842a.429.429 0 0 0-.41-.437.425.425 0 0 0-.428.445Zm-3.836.16a.79.79 0 0 1 .811-.883.666.666 0 0 1 .742.594h-.361a.348.348 0 0 0-.375-.309c-.189 0-.449.1-.449.6 0 .273.117.564.432.564a.4.4 0 0 0 .393-.375h.361a.709.709 0 0 1-.754.658.774.774 0 0 1-.796-.837Zm-.641.646a.831.831 0 0 1-.57.2.5.5 0 0 1-.562-.48c0-.408.326-.479.629-.51.266-.047.492-.018.492-.23 0-.189-.189-.225-.338-.225-.2 0-.344.082-.363.26h-.361c.029-.42.387-.545.748-.545.32 0 .658.131.658.475v.848c0 .088.018.125.082.125a.27.27 0 0 0 .09-.012v.254a.967.967 0 0 1-.227.041c-.144.009-.244-.044-.273-.192Zm-.475-.568c-.154.023-.3.082-.3.271 0 .166.207.215.332.215.16 0 .41-.084.41-.314v-.268a1.338 1.338 0 0 1-.437.104Zm-2.152.5H9.37v.225h-.344V6.839h.361v.838h.006a.6.6 0 0 1 .492-.256.768.768 0 0 1 .766.871c0 .445-.221.859-.707.859a.58.58 0 0 1-.563-.265Zm0-.594c0 .332.166.582.463.582.326 0 .455-.3.455-.582s-.158-.58-.455-.58-.458.237-.458.587Zm-3.262-.012c0-.592.357-.854.713-.854a.628.628 0 0 1 .545.256h.006v-.838h.361v2.266h-.338v-.219h-.006a.558.558 0 0 1-.51.266.772.772 0 0 1-.766-.87Zm.363.029c0 .285.141.564.455.564s.463-.3.463-.582c0-.361-.178-.58-.457-.58-.333.009-.456.309-.456.609Zm-2.828.646a.831.831 0 0 1-.57.2.5.5 0 0 1-.562-.48c0-.408.326-.479.635-.51.26-.047.492-.018.492-.23 0-.189-.2-.225-.344-.225-.2 0-.344.082-.357.26h-.361c.023-.42.381-.545.742-.545.32 0 .658.131.658.475v.848c0 .088.018.125.088.125a.294.294 0 0 0 .09-.012v.254a1.016 1.016 0 0 1-.232.041.245.245 0 0 1-.274-.193Zm-.475-.568c-.154.023-.3.082-.3.271 0 .166.207.215.338.215.154 0 .4-.084.4-.314v-.268a1.338 1.338 0 0 1-.432.103Zm103.018.32v-.967h-.273v-.273h.273v-.486h.361v.486h.326v.273h-.326v.877c0 .148.012.225.172.225a.685.685 0 0 0 .154-.012v.279c-.076.006-.154.018-.236.018-.37.007-.44-.141-.446-.412Zm-22.41 0v-.967h-.273v-.273h.273v-.486h.361v.486h.326v.273h-.326v.877c0 .148.012.225.172.225a.668.668 0 0 0 .154-.012v.279c-.078.006-.154.018-.232.018-.374.007-.444-.141-.45-.412Zm-2.822 0v-.967h-.273v-.273h.273v-.486h.361v.486h.326v.273h-.326v.877c0 .148.012.225.172.225a.685.685 0 0 0 .154-.012v.279c-.078.006-.154.018-.232.018-.374.007-.444-.141-.45-.412Zm-7.707 0v-.967h-.273v-.273h.273v-.486h.361v.486h.326v.273h-.326v.877c0 .148.012.225.178.225a.643.643 0 0 0 .148-.012v.279c-.078.006-.154.018-.232.018-.374.007-.444-.141-.45-.412Zm-10.412 0v-.967h-.271v-.273h.271v-.486h.367v.486h.326v.273h-.326v.877c0 .148.012.225.172.225a.7.7 0 0 0 .154-.012v.279c-.082.006-.16.018-.236.018-.373.007-.446-.141-.452-.412Zm-5.7 0v-.967h-.273v-.273h.273v-.486h.361v.486h.326v.273h-.326v.877c0 .148.012.225.172.225a.677.677 0 0 0 .154-.012v.279c-.082.006-.154.018-.236.018-.367.007-.444-.141-.449-.412Zm-17.479 0v-.967h-.271v-.273h.271v-.486h.363v.486h.324v.273h-.324v.877c0 .148.012.225.172.225a.643.643 0 0 0 .152-.012v.279c-.076.006-.152.018-.23.018-.377.007-.449-.141-.455-.412Zm-14.293 0v-.967h-.273v-.273h.273v-.486h.361v.486h.326v.273h-.326v.877c0 .148.012.225.172.225a.685.685 0 0 0 .154-.012v.279c-.078.006-.154.018-.232.018-.377.007-.447-.141-.453-.412Zm79.973.4V8.07c-.006-.256-.107-.367-.32-.367a.4.4 0 0 0-.4.432v.967h-.361V7.459h.344v.244l.006.006a.6.6 0 0 1 .51-.291.518.518 0 0 1 .582.557v1.127Zm-3.588 0v-.955c0-.266-.018-.443-.3-.443-.248 0-.35.16-.35.438v.961h-.361V8.047c0-.221-.07-.344-.291-.344a.381.381 0 0 0-.355.426v.973h-.367V7.459h.344v.232h.012a.551.551 0 0 1 .5-.273.474.474 0 0 1 .463.273.593.593 0 0 1 .516-.273.48.48 0 0 1 .545.551v1.133Zm-2.762 0V8.07c-.006-.256-.107-.367-.32-.367a.4.4 0 0 0-.4.432v.967h-.361V7.459h.344v.244l.006.006a.6.6 0 0 1 .51-.291.518.518 0 0 1 .582.557v1.127Zm-2.254 0V7.458h.338v.32h.006a.526.526 0 0 1 .48-.361.548.548 0 0 1 .137.012v.35a.733.733 0 0 0-.154-.018c-.248 0-.445.2-.445.563v.777Zm-2.977 0-.6-1.637h.391l.416 1.258h.006l.4-1.258h.373l-.586 1.637Zm-21.367 0V7.458h.357v1.643Zm-.758 0V8.07c-.006-.256-.1-.367-.314-.367a.4.4 0 0 0-.4.432v.967h-.363V7.459h.344v.244l.008.006a.6.6 0 0 1 .516-.291.517.517 0 0 1 .58.557v1.127Zm-6.76 0V8.07c-.006-.256-.111-.367-.32-.367a.4.4 0 0 0-.4.432v.967h-.367V6.836h.367v.844h.006a.567.567 0 0 1 .492-.262.519.519 0 0 1 .582.557v1.127Zm-3.912 0V7.732h-.273v-.273h.273v-.131c0-.42.219-.492.451-.492a.882.882 0 0 1 .254.025v.277a.644.644 0 0 0-.166-.018c-.1 0-.178.035-.178.172v.166h.309v.273h-.309V9.1Zm-4.689 0V7.458h.361v1.643Zm-4.779 0V7.458h.338v.32h.012a.518.518 0 0 1 .475-.361.548.548 0 0 1 .137.012v.35a.655.655 0 0 0-.154-.018c-.248 0-.445.2-.445.563v.777Zm-5.33 0V8.07c-.006-.256-.111-.367-.32-.367a.4.4 0 0 0-.4.432v.967h-.361V7.459h.344v.244l.006.006a.6.6 0 0 1 .516-.291.517.517 0 0 1 .58.557v1.127Zm-4.475 0V8.07c0-.256-.107-.367-.32-.367a.4.4 0 0 0-.4.432v.967h-.361V6.836h.361v.844h.006a.583.583 0 0 1 .492-.262.516.516 0 0 1 .582.557v1.127Zm-2.895 0V7.458h.367v1.643Zm-2.662 0V7.732h-.271v-.273h.271v-.131c0-.42.215-.492.451-.492a.928.928 0 0 1 .254.025v.277a.644.644 0 0 0-.166-.018c-.1 0-.178.035-.178.172v.166h.309v.273h-.309V9.1Zm-1.748 0V6.835h.361v2.266Zm-.766 0V6.835h.361v2.266Zm-2.727 0V7.732h-.268v-.273h.268v-.131c0-.42.219-.492.457-.492a.938.938 0 0 1 .254.025v.277a.662.662 0 0 0-.172-.018c-.094 0-.178.035-.178.172v.166h.309v.273h-.309V9.1Zm-3.5 0V8.07c-.006-.256-.107-.367-.32-.367a.4.4 0 0 0-.4.432v.967h-.363V6.836h.363v.844h.006a.577.577 0 0 1 .492-.262.517.517 0 0 1 .58.557v1.127Zm-11.811 0-.5-.795-.219.209v.586h-.361V6.835h.361v1.287l.658-.658h.443l-.633.6.693 1.037Zm-10.133 0V8.07c-.006-.256-.105-.367-.318-.367a.4.4 0 0 0-.4.432v.967H4.37V7.459h.344v.244l.006.006a.6.6 0 0 1 .51-.291.519.519 0 0 1 .582.557v1.127Zm66.941-1.92v-.346h.357v.346Zm-16.119 0v-.346h.361v.346Zm-17.479 0v-.346h.367v.346Zm9.557-1.258v-.3a.828.828 0 0 0 .172.023c.166 0 .209-.088.25-.23l.041-.125-.623-1.637h.4l.432 1.223h.006l.416-1.223h.379l-.641 1.727c-.117.3-.2.568-.58.568a1.723 1.723 0 0 1-.246-.016Zm-15.3-.492h.361c.047.207.213.244.4.244a.374.374 0 0 0 .422-.422v-.248h-.006a.571.571 0 0 1-.492.289c-.521 0-.736-.4-.736-.865a.756.756 0 0 1 .742-.824.513.513 0 0 1 .486.273h.006v-.227h.361v1.555c0 .492-.291.734-.807.734-.329.011-.696-.114-.731-.499Zm.309-.967c0 .268.129.541.432.541.32 0 .439-.291.439-.57s-.125-.545-.439-.545-.427.307-.427.584Zm51.775 1.139a.29.29 0 0 0 .207-.309h-.219v-.432h.443v.432a.5.5 0 0 1-.432.5Zm-6.469-.006v-.248a.709.709 0 0 1-.771-.742h.363c0 .279.117.445.408.451v-.766c-.35-.094-.723-.236-.723-.7a.653.653 0 0 1 .723-.623v-.248h.137v.248a.618.618 0 0 1 .693.623h-.361c-.012-.219-.107-.338-.332-.338v.67c.385.1.752.25.752.705a.7.7 0 0 1-.752.719v.248Zm.137-.539c.225-.012.391-.119.391-.373 0-.238-.2-.314-.391-.363Zm-.5-1.488c0 .207.184.279.361.32v-.635c-.223.01-.353.1-.353.325Zm11.127.611c0-.5.131-1.156.771-1.156s.766.652.766 1.156-.131 1.156-.766 1.156-.763-.642-.763-1.146Zm.363 0c0 .461.088.854.408.854s.4-.393.4-.854-.09-.855-.4-.855-.4.402-.4.865Zm-2.129 0c0-.5.131-1.156.771-1.156s.77.652.77 1.156-.131 1.156-.77 1.156-.763-.642-.763-1.146Zm.361 0c0 .461.09.854.41.854s.4-.393.4-.854-.084-.855-.4-.855-.402.402-.402.865Zm-2.123 0c0-.5.131-1.156.766-1.156s.771.652.771 1.156-.131 1.156-.771 1.156-.758-.642-.758-1.146Zm.363 0c0 .461.088.854.4.854s.408-.393.408-.854-.088-.855-.408-.855-.392.402-.392.865Zm-3.014 0c0-.5.125-1.156.766-1.156s.771.652.771 1.156-.131 1.156-.771 1.156-.757-.642-.757-1.146Zm.363 0c0 .461.088.854.4.854s.41-.393.41-.854-.09-.855-.41-.855-.387.402-.387.865Zm-2.129 0c0-.5.131-1.156.764-1.156s.771.652.771 1.156-.131 1.156-.771 1.156-.755-.642-.755-1.146Zm.361 0c0 .461.09.854.4.854s.41-.393.41-.854-.09-.855-.41-.855-.39.402-.39.865Zm-7.494.586h.361c.018.207.178.285.369.285.141 0 .379-.029.367-.221s-.273-.207-.539-.271-.523-.148-.523-.486c0-.355.387-.469.682-.469.338 0 .646.143.689.5h-.381c-.029-.172-.172-.219-.332-.219-.105 0-.295.023-.295.172 0 .178.266.2.533.26s.527.154.527.48c0 .393-.391.535-.734.535-.4.014-.709-.171-.715-.556Zm-.635.367a.848.848 0 0 1-.568.2.5.5 0 0 1-.562-.48c0-.41.326-.475.633-.51.256-.049.492-.02.492-.232 0-.189-.2-.225-.344-.225-.2 0-.344.082-.361.26h-.361c.023-.42.385-.545.746-.545.32 0 .658.131.658.475v.848c0 .09.018.125.084.125a.506.506 0 0 0 .088-.006v.248a.953.953 0 0 1-.225.043c-.14.012-.245-.042-.27-.191Zm-.473-.568c-.16.029-.3.082-.3.273 0 .166.207.213.332.213.16 0 .408-.084.408-.314V4.47a1.326 1.326 0 0 1-.43.106Zm-2.414-.09a.807.807 0 0 1 .795-.871.816.816 0 0 1 .775.961h-1.209a.437.437 0 0 0 .439.486.385.385 0 0 0 .4-.273h.344a.725.725 0 0 1-.746.559.775.775 0 0 1-.788-.852Zm.361-.148h.842a.421.421 0 1 0-.842 0Zm-3.717.807a.817.817 0 0 1-.568.2.5.5 0 0 1-.559-.48c0-.41.326-.475.629-.51.262-.049.492-.02.492-.232 0-.189-.189-.225-.338-.225-.2 0-.344.082-.361.26h-.361c.023-.42.385-.545.746-.545.32 0 .658.131.658.475v.848c0 .09.018.125.084.125a.506.506 0 0 0 .088-.006v.248a.953.953 0 0 1-.225.043.251.251 0 0 1-.275-.192Zm-.469-.568c-.154.029-.3.082-.3.273 0 .166.209.213.332.213.16 0 .41-.084.41-.314v-.268a1.338 1.338 0 0 1-.431.105Zm-3.414-.1a.831.831 0 1 1 .83.867.794.794 0 0 1-.819-.854Zm.361 0c0 .285.148.582.469.582s.469-.3.469-.582-.143-.58-.469-.58-.458.31-.458.593Zm-4.238-.012c0-.592.35-.854.705-.854a.65.65 0 0 1 .551.256h.006v-.836h.361v2.27h-.344v-.225h-.006a.543.543 0 0 1-.51.268c-.504.013-.75-.374-.75-.866Zm.361.029c0 .285.135.564.449.564s.463-.3.463-.582c0-.361-.178-.58-.457-.58-.327.014-.444.317-.444.612Zm-2.129-.012a.793.793 0 1 1 1.564.09h-1.2a.437.437 0 0 0 .439.486.385.385 0 0 0 .4-.273h.344a.725.725 0 0 1-.746.559.775.775 0 0 1-.79-.848Zm.361-.148h.842a.421.421 0 1 0-.842 0Zm-3.172.363V3.648h.361v1.008c0 .285.119.393.314.393.3 0 .4-.2.4-.445v-.955h.361v1.643h-.355v-.23h-.006a.551.551 0 0 1-.469.273c-.414.012-.594-.203-.594-.634Zm-1.736.076h.361c.023.207.178.285.373.285.137 0 .373-.029.367-.221s-.277-.207-.539-.271-.527-.148-.527-.486c0-.355.391-.469.688-.469a.609.609 0 0 1 .688.5h-.379c-.035-.172-.178-.219-.332-.219-.107 0-.3.023-.3.172 0 .178.268.2.533.26s.533.154.533.48c0 .393-.4.535-.734.535-.404.018-.715-.167-.721-.552Zm-7.287.367a.827.827 0 0 1-.568.2.5.5 0 0 1-.559-.48c0-.41.326-.475.629-.51.262-.049.492-.02.492-.232 0-.189-.189-.225-.338-.225-.2 0-.344.082-.361.26h-.361c.023-.42.385-.545.746-.545.32 0 .658.131.658.475v.848c0 .09.018.125.084.125a.506.506 0 0 0 .088-.006v.248a.953.953 0 0 1-.225.043.251.251 0 0 1-.27-.187Zm-.469-.568c-.154.029-.3.082-.3.273 0 .166.209.213.332.213.16 0 .41-.084.41-.314v-.268a1.372 1.372 0 0 1-.431.11Zm-3.533-.09a.807.807 0 0 1 .795-.871.816.816 0 0 1 .775.961h-1.209a.437.437 0 0 0 .439.486.385.385 0 0 0 .4-.273h.344a.725.725 0 0 1-.746.559.778.778 0 0 1-.787-.848Zm.361-.148h.842a.421.421 0 1 0-.842 0Zm-2.3.131c0-.592.352-.854.713-.854a.647.647 0 0 1 .545.256h.006v-.836h.361v2.27h-.344v-.225h-.006a.543.543 0 0 1-.51.268c-.509.013-.754-.374-.754-.866Zm.363.029c0 .285.135.564.455.564s.457-.3.457-.582c0-.361-.178-.58-.451-.58-.333.014-.45.317-.45.612Zm-2.129-.012a.8.8 0 1 1 1.57.09h-1.209a.44.44 0 0 0 .439.486.385.385 0 0 0 .4-.273h.344a.725.725 0 0 1-.746.559.775.775 0 0 1-.787-.848Zm.361-.148h.842a.421.421 0 1 0-.842 0Zm-3.906.439h.367c.018.207.178.285.367.285.137 0 .379-.029.367-.221s-.271-.207-.539-.271-.527-.148-.527-.486c0-.355.391-.469.688-.469a.609.609 0 0 1 .688.5h-.379c-.029-.172-.172-.219-.332-.219-.107 0-.3.023-.3.172 0 .178.268.2.539.26s.527.154.527.48c0 .393-.4.535-.734.535-.406.018-.715-.167-.721-.552Zm-6.754.367a.827.827 0 0 1-.568.2.5.5 0 0 1-.559-.48c0-.41.326-.475.629-.51.262-.049.492-.02.492-.232 0-.189-.2-.225-.338-.225-.207 0-.35.082-.361.26h-.361c.023-.42.385-.545.746-.545.32 0 .652.131.652.475v.848c0 .09.023.125.09.125a.541.541 0 0 0 .088-.006v.248a.946.946 0 0 1-.23.043.248.248 0 0 1-.269-.187Zm-.475-.568c-.154.029-.295.082-.295.273 0 .166.207.213.338.213.154 0 .4-.084.4-.314v-.268a1.306 1.306 0 0 1-.431.11Zm-2.3.2h.361c.018.207.178.285.367.285.137 0 .379-.029.367-.221s-.271-.207-.539-.271-.527-.148-.527-.486c0-.355.391-.469.688-.469a.609.609 0 0 1 .688.5h-.379c-.029-.172-.172-.219-.332-.219-.107 0-.3.023-.3.172 0 .178.268.2.533.26s.527.154.527.48c0 .393-.391.535-.734.535-.395.019-.701-.166-.707-.551Zm-3.736-.076V3.647h.361v1.008c0 .285.119.393.314.393.3 0 .4-.2.4-.445v-.955h.361v1.643h-.355v-.23h-.006a.551.551 0 0 1-.469.273c-.41.013-.594-.202-.594-.633Zm-1.963-.221a.831.831 0 1 1 .83.867.794.794 0 0 1-.817-.852Zm.363 0c0 .285.141.582.467.582s.469-.3.469-.582-.143-.58-.469-.58-.454.312-.454.595Zm56.2.416v-.967h-.271v-.268h.271v-.492h.361v.492h.326v.268h-.326v.877c0 .148.012.227.178.227a.627.627 0 0 0 .148-.012v.277c-.076.006-.154.018-.23.018-.369.013-.441-.128-.447-.405Zm-7.885 0v-.967h-.273v-.268h.273v-.492h.361v.492h.326v.268h-.326v.877c0 .148.012.227.178.227a.627.627 0 0 0 .148-.012v.277c-.076.006-.154.018-.23.018-.37.013-.44-.128-.447-.405Zm-5.59 0v-.967h-.273v-.268h.273v-.492h.361v.492h.326v.268h-.326v.877c0 .148.012.227.178.227a.643.643 0 0 0 .148-.012v.277c-.078.006-.154.018-.232.018-.368.013-.439-.128-.448-.405Zm17.6.408v-1.57h-.545v-.285c.307.006.6-.1.646-.367h.3V5.29Zm-10.162 0v-2.27h.361v2.27Zm-13.191 0V3.646h.338v.314h.006a.532.532 0 0 1 .48-.361.6.6 0 0 1 .137.012v.35c-.055-.006-.107-.018-.154-.018-.25 0-.445.2-.445.564v.781Zm-4.215 0V4.252c-.006-.254-.107-.367-.32-.367a.4.4 0 0 0-.4.432v.973h-.361V3.647h.344v.238l.006.006a.6.6 0 0 1 .51-.291.52.52 0 0 1 .582.564v1.125Zm-1.838 0V3.646h.361v1.643Zm-3.3 0v-2.27h.361v2.27Zm-.766 0v-2.27h.363v2.27Zm-2.893 0V3.646h.338v.314h.012a.53.53 0 0 1 .475-.361.548.548 0 0 1 .137.012v.35a1.24 1.24 0 0 0-.154-.018c-.25 0-.445.2-.445.564v.781Zm-6.361 0V3.914h-.273v-.268h.273v-.141c0-.416.219-.486.451-.486a.925.925 0 0 1 .254.023v.285a.416.416 0 0 0-.166-.02c-.1 0-.178.031-.178.166v.172h.309v.268h-.309v1.375Zm-5.266 0V4.252c-.006-.254-.111-.367-.324-.367a.4.4 0 0 0-.393.432v.973h-.361V3.647h.338v.238l.006.006a.6.6 0 0 1 .516-.291.521.521 0 0 1 .582.564v1.125Zm-1.838 0V3.646h.363v1.643Zm-1.221 0-.6-1.643h.391l.42 1.258h.006l.4-1.258h.373l-.586 1.643Zm-5.852 0V3.646h.344v.314h.006a.532.532 0 0 1 .48-.361.524.524 0 0 1 .131.012v.35a1.24 1.24 0 0 0-.154-.018c-.244 0-.445.2-.445.564v.781Zm-4.832 0V4.4l-.848-1.381h.457l.6 1.014.588-1.014h.445L18.977 4.4v.889Zm32.324-1.926v-.344h.361v.344Zm-20.42 0v-.344h.363v.344Z\" \/>\n    <path fill=\"#022164\" d=\"M109.083 44.659H1.047V1.024H109.1ZM110.051 0H0v45.736h110.05Z\" \/>\n  \t<\/svg>\n\t\t\t\t\t\t\t<p>Esta cooperativa de cr\u00e9dito est\u00e1 asegurada a nivel federal por la Administraci\u00f3n Nacional de Cooperativas de Cr\u00e9dito.<\/p>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":0,"parent":2514,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"class_list":["post-2519","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Savings &amp; Money Market Accounts - Patriot Federal Credit Union<\/title>\n<meta name=\"description\" content=\"Patriot Federal Credit Union savings and money market accounts are a great option to earn interest on your deposits while enjoying unlimited withdrawals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Savings &amp; Money Market Accounts - Patriot Federal Credit Union\" \/>\n<meta property=\"og:description\" content=\"Patriot Federal Credit Union savings and money market accounts are a great option to earn interest on your deposits while enjoying unlimited withdrawals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/\" \/>\n<meta property=\"og:site_name\" content=\"Patriot Federal Credit Union\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T13:46:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/personal\\\/savings-money-market-accounts\\\/\",\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/personal\\\/savings-money-market-accounts\\\/\",\"name\":\"Savings & Money Market Accounts - Patriot Federal Credit Union\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#website\"},\"datePublished\":\"2023-08-18T23:26:33+00:00\",\"dateModified\":\"2026-08-27T13:46:38+00:00\",\"description\":\"Patriot Federal Credit Union savings and money market accounts are a great option to earn interest on your deposits while enjoying unlimited withdrawals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/personal\\\/savings-money-market-accounts\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patriotfcu.org\\\/personal\\\/savings-money-market-accounts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/personal\\\/savings-money-market-accounts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patriotfcu.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personal\",\"item\":\"https:\\\/\\\/www.patriotfcu.org\\\/personal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Savings &#038; Money Market Accounts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#website\",\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/\",\"name\":\"Patriot Federal Credit Union\",\"description\":\"Financial Services That Meet Your Need\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patriotfcu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuentas de ahorro y mercado monetario - Patriot Federal Credit Union","description":"Las cuentas de ahorro y de mercado monetario de Patriot Federal Credit Union son una excelente opci\u00f3n para ganar intereses sobre sus dep\u00f3sitos mientras disfruta de retiros ilimitados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/","og_locale":"es_ES","og_type":"article","og_title":"Savings & Money Market Accounts - Patriot Federal Credit Union","og_description":"Patriot Federal Credit Union savings and money market accounts are a great option to earn interest on your deposits while enjoying unlimited withdrawals.","og_url":"https:\/\/www.patriotfcu.org\/es\/personal\/cuentas-de-ahorro-del-mercado-monetario\/","og_site_name":"Patriot Federal Credit Union","article_modified_time":"2026-08-27T13:46:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.patriotfcu.org\/personal\/savings-money-market-accounts\/","url":"https:\/\/www.patriotfcu.org\/personal\/savings-money-market-accounts\/","name":"Cuentas de ahorro y mercado monetario - Patriot Federal Credit Union","isPartOf":{"@id":"https:\/\/www.patriotfcu.org\/#website"},"datePublished":"2023-08-18T23:26:33+00:00","dateModified":"2026-08-27T13:46:38+00:00","description":"Las cuentas de ahorro y de mercado monetario de Patriot Federal Credit Union son una excelente opci\u00f3n para ganar intereses sobre sus dep\u00f3sitos mientras disfruta de retiros ilimitados.","breadcrumb":{"@id":"https:\/\/www.patriotfcu.org\/personal\/savings-money-market-accounts\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patriotfcu.org\/personal\/savings-money-market-accounts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patriotfcu.org\/personal\/savings-money-market-accounts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patriotfcu.org\/"},{"@type":"ListItem","position":2,"name":"Personal","item":"https:\/\/www.patriotfcu.org\/personal\/"},{"@type":"ListItem","position":3,"name":"Savings &#038; Money Market Accounts"}]},{"@type":"WebSite","@id":"https:\/\/www.patriotfcu.org\/#website","url":"https:\/\/www.patriotfcu.org\/","name":"Patriot Federal Credit Union","description":"Servicios financieros que satisfacen sus necesidades","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patriotfcu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/pages\/2519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/comments?post=2519"}],"version-history":[{"count":9,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/pages\/2519\/revisions"}],"predecessor-version":[{"id":7979,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/pages\/2519\/revisions\/7979"}],"up":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/pages\/2514"}],"wp:attachment":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/media?parent=2519"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}