{"id":3548,"date":"2023-11-09T14:57:00","date_gmt":"2023-11-09T19:57:00","guid":{"rendered":"https:\/\/patriotfcu.pixelspoke-staging.com\/?p=3548"},"modified":"2024-05-02T11:54:53","modified_gmt":"2024-05-02T15:54:53","slug":"veteranos-y-estafas","status":"publish","type":"post","link":"https:\/\/www.patriotfcu.org\/es\/blog\/veterans-and-scams\/","title":{"rendered":"Veteranos y estafas"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__blog-post-hero\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"single_post--header co-post_hero light co-page_hero__has_image\" aria-label=\"Encabezado de la publicaci\u00f3n: Veteranos y estafas\">\n\t\t<h1 class=\"single_post--title\">Veteranos y estafas<\/h1>\n\t\t<p class=\"single_post--category\"><a href=\"https:\/\/www.patriotfcu.org\/es\/blog\/category\/fraud-security\/\" rel=\"category tag\">Fraude y seguridad<\/a><\/p>\n\t\t<p class=\"single_post--date\">noviembre 9, 2023<\/p>\n\t\t<div class=\"single_post--social-share\">Compartir en<div class=\"co-social_share a2a_kit a2a_default_style\">\n\t\t\t<a\n\t\t\tclass=\"co-social--link\t\t\t\tjs-share_button\t\t\t\ttrusted\"\n\t\t\tdata-shareurl=\"https:\/\/www.patriotfcu.org\/es\/blog\/veterans-and-scams\/\"\n\t\t\tdata-sharetitle=\"Veterans and Scams\"\n\t\t\tdata-shareservice=\"facebook\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17.738\" height=\"32.746\" viewbox=\"0 0 17.738 32.746\">\n  <path id=\"Path_690\" data-name=\"Path 690\" d=\"M89.242,351.968H83.868c-.59,0-1.269.715-1.269,1.787V356.4h6.648v6.648H82.6v15.013h-6.21V363.049h-4.88V356.4h4.88v-2.59c0-4.469,3.355-8.494,7.479-8.494h5.374Z\" transform=\"translate(-71.509 -345.317)\" fill=\"#2b6ea5\"\/>\n<\/svg>\n\t\t<\/a>\n\t\t\t\t<a\n\t\t\tclass=\"co-social--link\t\t\t\tjs-share_button\t\t\t\ttrusted\"\n\t\t\tdata-shareurl=\"https:\/\/www.patriotfcu.org\/es\/blog\/veterans-and-scams\/\"\n\t\t\tdata-sharetitle=\"Veterans and Scams\"\n\t\t\tdata-shareservice=\"linkedin\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"29.324\" height=\"29.282\" viewbox=\"0 0 29.324 29.282\">\n  <path id=\"Path_689\" data-name=\"Path 689\" d=\"M496.424,377.52h-6.047V358h6.047Zm-3.048-22.078a3.6,3.6,0,1,1,3.571-3.632v.032a3.587,3.587,0,0,1-3.571,3.6m25.692,22.078h-6.012V367.272c0-2.81-1.069-4.379-3.29-4.379-2.421,0-3.681,1.635-3.681,4.379v10.248h-5.8V358h5.8v2.629a6.8,6.8,0,0,1,5.879-3.225c4.141,0,7.1,2.528,7.1,7.756Z\" transform=\"translate(-489.743 -348.239)\" fill=\"#2b6ea5\"\/>\n<\/svg>\n\t\t<\/a>\n\t\t<\/div><\/div>\n\t\t\t\t<div class=\"single_post--img_wrap\">\n\t\t\t<div class=\"single_post--img_wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"721\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4.jpg\" class=\"attachment-full size-full\" alt=\"Soldado en la cima de una monta\u00f1a\"  srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4.jpg 1100w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-540x354.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-730x478.jpg 730w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-768x503.jpg 768w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-18x12.jpg 18w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-396x260.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-800x524.jpg 800w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Untitled-design-4-75x49.jpg 75w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/div>\t\t<\/div>\n\t\t<p class=\"single_post--summary\">\n\t\t\tA medida que nos acercamos al D\u00eda de los Veteranos, agradecemos a nuestros veteranos por su servicio y sacrificio. Pero no todo el mundo tiene en mente los mejores intereses del veterinario. Ya sea que haya dejado el servicio hace d\u00e9cadas o est\u00e9 planeando su transici\u00f3n a la vida civil, los estafadores intentar\u00e1n que env\u00ede dinero o comparta informaci\u00f3n personal. Los estafadores tambi\u00e9n quieren apoderarse de los valiosos beneficios que usted obtuvo mediante el servicio militar. \u00bfCu\u00e1les son algunas formas de saber que est\u00e1s tratando con un estafador?\t\t<\/p>\n\t<\/header><!-- .entry_header -->\n\t\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__long-form-text\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-long_form\">\n\t\t\t\t\t<div class=\"co-long_form--block co-long_form--block__nomedia prow items-start justify-center\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:12\">\n\t\t\t\t\t<div class=\"co-long_form--content\"><p>Primero sepa c\u00f3mo operan los estafadores. Las estafas de impostores vienen en muchas variedades, pero funcionan de la misma manera: los estafadores llaman, env\u00edan mensajes de texto, env\u00edan correos electr\u00f3nicos o se comunican a trav\u00e9s de las redes sociales y se hacen pasar por alguien en quien usted conf\u00eda para convencerlo de que les env\u00ede dinero. Los estafadores pueden pretender ser de un\u00a0<a href=\"http:\/\/consumer.ftc.gov\/articles\/how-avoid-government-impersonator-scam\" target=\"_blank\" rel=\"noopener\" aria-label=\"agencia gubernamental - se abre en una pesta\u00f1a nueva\" data-uw-rm-ext-link=\"\">agencia del gobierno<\/a>\u00a0y decir que tienes que pagar una multa. O pueden hacerse pasar por un\u00a0<a href=\"https:\/\/consumer.ftc.gov\/articles\/what-know-about-romance-scams\" target=\"_blank\" rel=\"noopener\" aria-label=\"inter\u00e9s amoroso - se abre en una pesta\u00f1a nueva\" data-uw-rm-ext-link=\"\">inter\u00e9s amoroso<\/a>\u00a0que necesita que env\u00edes dinero para un costoso procedimiento m\u00e9dico. El estafador puede\u00a0<a href=\"https:\/\/consumer.ftc.gov\/articles\/job-scams\" target=\"_blank\" rel=\"noopener\" aria-label=\"ofrecerle un trabajo - se abre en una pesta\u00f1a nueva\" data-uw-rm-ext-link=\"\">ofrecerte un trabajo<\/a>, tambi\u00e9n, pero diga que debe pagar una tarifa antes de ser contratado. Los estafadores pueden afirmar que tienen cierta afinidad con el ej\u00e9rcito para ganarse su confianza y no profundizar demasiado en lo que dicen.<\/p>\n<p>En segundo lugar, sepa c\u00f3mo le piden que pague los estafadores. No importa cu\u00e1l sea la historia, s\u00f3lo los estafadores insistir\u00e1n en que la \u00fanica forma de pagar es en efectivo, tarjeta de regalo, criptomoneda, aplicaci\u00f3n de pago o servicio de transferencia bancaria. Estos m\u00e9todos hacen que sea casi imposible recuperar su dinero, raz\u00f3n por la cual los estafadores insisten en que pague de esa manera. Detener. No pagues.<\/p>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Esta cooperativa de cr\u00e9dito est\u00e1 asegurada a nivel federal por la Administraci\u00f3n Nacional de Cooperativas de Cr\u00e9dito.<\/p>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Prestamista de vivienda equitativa<\/p>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A medida que nos acercamos al D\u00eda de los Veteranos, agradecemos a nuestros veteranos por su servicio y sacrificio. Pero no todo el mundo tiene en mente los mejores intereses del veterinario. Ya sea que haya dejado el servicio hace d\u00e9cadas o est\u00e9 planeando su transici\u00f3n a la vida civil, los estafadores intentar\u00e1n que env\u00ede dinero o comparta informaci\u00f3n personal. Los estafadores tambi\u00e9n quieren apoderarse de los valiosos beneficios que usted obtuvo mediante el servicio militar. \u00bfCu\u00e1les son algunas formas de saber que est\u00e1s tratando con un estafador? <a href=\"https:\/\/www.patriotfcu.org\/es\/blog\/veterans-and-scams\/\">sigue leyendo <span class=\"meta-nav\">\u2192<\/span><\/a><\/p>","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-3548","post","type-post","status-publish","format-standard","hentry","category-fraud-security"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veterans and Scams - Patriot Federal Credit Union<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patriotfcu.org\/es\/blog\/veteranos-y-estafas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veterans and Scams - Patriot Federal Credit Union\" \/>\n<meta property=\"og:description\" content=\"As we approach Veterans Day, we thank our veterans for their service and sacrifice. But not everyone has a vet\u2019s best interests in mind. Whether you left the service decades ago or you\u2019re planning your transition to civilian life, scammers will try to get you to send money or share personal information. Scammers also want to get their hands on the valuable benefits you earned through military service. What are some ways to know you\u2019re dealing with a scammer? Continue reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patriotfcu.org\/es\/blog\/veteranos-y-estafas\/\" \/>\n<meta property=\"og:site_name\" content=\"Patriot Federal Credit Union\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T19:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T15:54:53+00:00\" \/>\n<meta name=\"author\" content=\"Ken Ditzler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Ditzler\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/\"},\"author\":{\"name\":\"Ken Ditzler\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#\\\/schema\\\/person\\\/64f7330195a0ff0acbd56677fe8baab3\"},\"headline\":\"Veterans and Scams\",\"datePublished\":\"2023-11-09T19:57:00+00:00\",\"dateModified\":\"2024-05-02T15:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/\"},\"wordCount\":3,\"articleSection\":[\"Fraud &amp; Security\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/\",\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/\",\"name\":\"Veterans and Scams - Patriot Federal Credit Union\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#website\"},\"datePublished\":\"2023-11-09T19:57:00+00:00\",\"dateModified\":\"2024-05-02T15:54:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#\\\/schema\\\/person\\\/64f7330195a0ff0acbd56677fe8baab3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/veterans-and-scams\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patriotfcu.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veterans and Scams\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#website\",\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/\",\"name\":\"Patriot Federal Credit Union\",\"description\":\"Financial Services That Meet Your Need\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patriotfcu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#\\\/schema\\\/person\\\/64f7330195a0ff0acbd56677fe8baab3\",\"name\":\"Ken Ditzler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g\",\"caption\":\"Ken Ditzler\"},\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/es\\\/blog\\\/author\\\/kditzler\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veteranos y estafas - Patriot Federal Credit Union","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patriotfcu.org\/es\/blog\/veteranos-y-estafas\/","og_locale":"es_ES","og_type":"article","og_title":"Veterans and Scams - Patriot Federal Credit Union","og_description":"As we approach Veterans Day, we thank our veterans for their service and sacrifice. But not everyone has a vet\u2019s best interests in mind. Whether you left the service decades ago or you\u2019re planning your transition to civilian life, scammers will try to get you to send money or share personal information. Scammers also want to get their hands on the valuable benefits you earned through military service. What are some ways to know you\u2019re dealing with a scammer? Continue reading &rarr;","og_url":"https:\/\/www.patriotfcu.org\/es\/blog\/veteranos-y-estafas\/","og_site_name":"Patriot Federal Credit Union","article_published_time":"2023-11-09T19:57:00+00:00","article_modified_time":"2024-05-02T15:54:53+00:00","author":"Ken Ditzler","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ken Ditzler"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/#article","isPartOf":{"@id":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/"},"author":{"name":"Ken Ditzler","@id":"https:\/\/www.patriotfcu.org\/#\/schema\/person\/64f7330195a0ff0acbd56677fe8baab3"},"headline":"Veterans and Scams","datePublished":"2023-11-09T19:57:00+00:00","dateModified":"2024-05-02T15:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/"},"wordCount":3,"articleSection":["Fraud &amp; Security"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/","url":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/","name":"Veteranos y estafas - Patriot Federal Credit Union","isPartOf":{"@id":"https:\/\/www.patriotfcu.org\/#website"},"datePublished":"2023-11-09T19:57:00+00:00","dateModified":"2024-05-02T15:54:53+00:00","author":{"@id":"https:\/\/www.patriotfcu.org\/#\/schema\/person\/64f7330195a0ff0acbd56677fe8baab3"},"breadcrumb":{"@id":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patriotfcu.org\/blog\/veterans-and-scams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patriotfcu.org\/"},{"@type":"ListItem","position":2,"name":"Veterans and Scams"}]},{"@type":"WebSite","@id":"https:\/\/www.patriotfcu.org\/#website","url":"https:\/\/www.patriotfcu.org\/","name":"Patriot Federal Credit Union","description":"Servicios financieros que satisfacen sus necesidades","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patriotfcu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.patriotfcu.org\/#\/schema\/person\/64f7330195a0ff0acbd56677fe8baab3","name":"Ken Ditzler","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g","caption":"Ken Ditzler"},"url":"https:\/\/www.patriotfcu.org\/es\/blog\/author\/kditzler\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/posts\/3548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/comments?post=3548"}],"version-history":[{"count":0,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/posts\/3548\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/media?parent=3548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/categories?post=3548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/tags?post=3548"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}