{"id":3586,"date":"2023-04-25T00:15:00","date_gmt":"2023-04-25T04:15:00","guid":{"rendered":"https:\/\/patriotfcu.pixelspoke-staging.com\/?p=3586"},"modified":"2024-05-02T11:54:54","modified_gmt":"2024-05-02T15:54:54","slug":"por-que-los-certificados-se-estan-volviendo-tan-populares","status":"publish","type":"post","link":"https:\/\/www.patriotfcu.org\/es\/blog\/why-are-certificates-becoming-so-popular\/","title":{"rendered":"\u00bfPor qu\u00e9 los certificados se est\u00e1n volviendo tan populares?"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__blog-post-hero\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"single_post--header co-post_hero light co-page_hero__has_image\" aria-label=\"Encabezado de la publicaci\u00f3n: \u00bfPor qu\u00e9 los certificados se est\u00e1n volviendo tan populares?\">\n\t\t<h1 class=\"single_post--title\">\u00bfPor qu\u00e9 los certificados se est\u00e1n volviendo tan populares?<\/h1>\n\t\t<p class=\"single_post--category\"><a href=\"https:\/\/www.patriotfcu.org\/es\/blog\/category\/personal-finance\/\" rel=\"category tag\">Finanzas personales<\/a><\/p>\n\t\t<p class=\"single_post--date\">25 de abril de 2023<\/p>\n\t\t<div class=\"single_post--social-share\">Compartir en<div class=\"co-social_share a2a_kit a2a_default_style\">\n\t\t\t<a\n\t\t\tclass=\"co-social--link\t\t\t\tjs-share_button\t\t\t\ttrusted\"\n\t\t\tdata-shareurl=\"https:\/\/www.patriotfcu.org\/es\/blog\/why-are-certificates-becoming-so-popular\/\"\n\t\t\tdata-sharetitle=\"Why are Certificates Becoming So Popular?\"\n\t\t\tdata-shareservice=\"facebook\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17.738\" height=\"32.746\" viewbox=\"0 0 17.738 32.746\">\n  <path id=\"Path_690\" data-name=\"Path 690\" d=\"M89.242,351.968H83.868c-.59,0-1.269.715-1.269,1.787V356.4h6.648v6.648H82.6v15.013h-6.21V363.049h-4.88V356.4h4.88v-2.59c0-4.469,3.355-8.494,7.479-8.494h5.374Z\" transform=\"translate(-71.509 -345.317)\" fill=\"#2b6ea5\"\/>\n<\/svg>\n\t\t<\/a>\n\t\t\t\t<a\n\t\t\tclass=\"co-social--link\t\t\t\tjs-share_button\t\t\t\ttrusted\"\n\t\t\tdata-shareurl=\"https:\/\/www.patriotfcu.org\/es\/blog\/why-are-certificates-becoming-so-popular\/\"\n\t\t\tdata-sharetitle=\"Why are Certificates Becoming So Popular?\"\n\t\t\tdata-shareservice=\"linkedin\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"29.324\" height=\"29.282\" viewbox=\"0 0 29.324 29.282\">\n  <path id=\"Path_689\" data-name=\"Path 689\" d=\"M496.424,377.52h-6.047V358h6.047Zm-3.048-22.078a3.6,3.6,0,1,1,3.571-3.632v.032a3.587,3.587,0,0,1-3.571,3.6m25.692,22.078h-6.012V367.272c0-2.81-1.069-4.379-3.29-4.379-2.421,0-3.681,1.635-3.681,4.379v10.248h-5.8V358h5.8v2.629a6.8,6.8,0,0,1,5.879-3.225c4.141,0,7.1,2.528,7.1,7.756Z\" transform=\"translate(-489.743 -348.239)\" fill=\"#2b6ea5\"\/>\n<\/svg>\n\t\t<\/a>\n\t\t<\/div><\/div>\n\t\t\t\t<div class=\"single_post--img_wrap\">\n\t\t\t<div class=\"single_post--img_wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"721\" src=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2.jpg\" class=\"attachment-full size-full\" alt=\"Mujer sosteniendo dinero frente a su cara\"  srcset=\"https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2.jpg 1100w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-540x354.jpg 540w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-730x478.jpg 730w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-768x503.jpg 768w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-18x12.jpg 18w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-396x260.jpg 396w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-800x524.jpg 800w, https:\/\/www.patriotfcu.org\/wp-content\/uploads\/Blog-Post-Image-2-Recovered-2-75x49.jpg 75w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/div>\t\t<\/div>\n\t\t<p class=\"single_post--summary\">\n\t\t\tDespu\u00e9s de un a\u00f1o de precios en alza, los miembros todav\u00eda est\u00e1n lidiando con los efectos del aumento de la inflaci\u00f3n. Si a eso le sumamos el desempe\u00f1o inestable de Wall Street, la gente busca un lado positivo. Una de esas oportunidades est\u00e1 empezando a brillar a medida que las tasas de ahorro tambi\u00e9n empiezan a subir: se llama Certificado de Acciones.\t\t<\/p>\n\t<\/header><!-- .entry_header -->\n\t\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__long-form-text\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-long_form\">\n\t\t\t\t\t<div class=\"co-long_form--block co-long_form--block__nomedia prow items-start justify-center\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:12\">\n\t\t\t\t\t<div class=\"co-long_form--content\"><p>Los certificados de acciones, tambi\u00e9n conocidos como cuentas de certificado o certificados entre muchas cooperativas de cr\u00e9dito, son cuentas de inversi\u00f3n que generan rendimientos m\u00e1s altos que las cuentas de ahorro tradicionales. Ofrecen una gama de ventajas financieras con muy pocos inconvenientes. Contin\u00fae leyendo para descubrir si agregar un Certificado a su plan de ahorro es adecuado para usted.<\/p>\n<h2>\u00bfQu\u00e9 es un <a href=\"https:\/\/www.patriotfcu.org\/es\/personal-banking\/certificados\/\">Certificado<\/a>?<\/h2>\n<p>La mayor\u00eda de las cooperativas de cr\u00e9dito y los bancos ofrecen tres cuentas principales de ahorro e inversi\u00f3n:<\/p>\n<ul>\n<li>Cuentas de ahorro tradicionales<\/li>\n<li>cuentas del mercado monetario<\/li>\n<li>Certificados<\/li>\n<\/ul>\n<p>Entre los tres, los certificados generalmente ofrecen los mayores rendimientos. Sin embargo, existe una compensaci\u00f3n a cambio de obtener mayores dividendos. Con un Certificado, su dinero est\u00e1 bloqueado, lo que significa que no puede acceder ni retirar sus fondos (sin incurrir en una multa). Si bien esta caracter\u00edstica de la cuenta puede parecer un inconveniente, a menudo es una bendici\u00f3n disfrazada porque te obliga a ahorrar dinero.<\/p>\n<h2>\u00bfC\u00f3mo funciona un certificado?<\/h2>\n<p>Debido a que su dinero est\u00e1 bloqueado por un per\u00edodo designado, los Certificados se dividen en distintos t\u00e9rminos. Por ejemplo, a menudo ver\u00e1 certificados mostrados de la siguiente manera:<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"242\"><strong>Plazo del certificado de acciones<\/strong><\/td>\n<td width=\"242\"><strong>APY o tasa de dividendos<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"242\">12 meses<\/td>\n<td width=\"242\">3.20%<\/td>\n<\/tr>\n<tr>\n<td width=\"242\">24 meses<\/td>\n<td width=\"242\">3.35%<\/td>\n<\/tr>\n<tr>\n<td width=\"242\">36 meses<\/td>\n<td width=\"242\">3.40%<\/td>\n<\/tr>\n<tr>\n<td width=\"242\">48 meses<\/td>\n<td width=\"242\">3.50%<\/td>\n<\/tr>\n<tr>\n<td width=\"242\">60 meses<\/td>\n<td width=\"242\">3.80%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2><em><u>Caracter\u00edsticas de los Certificados:<\/u><\/em><\/h2>\n<ul>\n<li>Si bien los plazos var\u00edan seg\u00fan la instituci\u00f3n financiera, normalmente oscilan entre seis meses y cinco a\u00f1os.<\/li>\n<li>Generalmente, cuanto m\u00e1s largo sea el plazo, mayor ser\u00e1 la tasa de rendimiento que obtendr\u00e1.<\/li>\n<li>Sus fondos est\u00e1n bloqueados durante su mandato. Puede acceder a sus fondos, pero deber\u00e1 pagar una multa. Esta pena puede variar entre instituciones. Patriot ofrece una penalizaci\u00f3n competitivamente baja. Solicite m\u00e1s detalles.<\/li>\n<li data-uw-rm-sr=\"\">La mayor\u00eda de los Certificados requieren un dep\u00f3sito m\u00ednimo, como $1,000. Patriot ofrece dos opciones de Certificado de Ahorro Continuo dise\u00f1adas para generar el dep\u00f3sito m\u00ednimo que solo requiere un dep\u00f3sito de $25 para abrirse.<\/li>\n<\/ul>\n<h2>Ventajas de los Certificados:<\/h2>\n<ul>\n<li data-uw-rm-sr=\"\">B\u00e1sicamente, no existe ning\u00fan riesgo al invertir en Certificados. Su cuenta est\u00e1 asegurada a nivel federal por la Administraci\u00f3n Nacional de Cooperativas de Cr\u00e9dito (NCUA) o la Corporaci\u00f3n Federal de Seguro de Dep\u00f3sitos (FDIC) hasta $250,000.<\/li>\n<li>Con rentabilidades garantizadas, son una excelente alternativa a la monta\u00f1a rusa del mercado de valores.<\/li>\n<li>Las tasas de dividendos generalmente son fijas, lo que significa que sabr\u00e1 exactamente cu\u00e1nto devolver\u00e1 su inversi\u00f3n durante su plazo.<\/li>\n<li>En caso de emergencia, puede retirar fondos de su cuenta de forma r\u00e1pida y sencilla. Sin embargo, dependiendo de la instituci\u00f3n financiera, es probable que incurra en una tarifa por retiro anticipado o pierda una parte de las ganancias de su cuenta.<\/li>\n<li>Los certificados lo obligan a ahorrar dinero al bloquear sus fondos hasta el final del plazo elegido. No puede recurrir a esta cuenta para gastos fr\u00edvolos como lo har\u00eda con una cuenta de ahorro tradicional o una cuenta del mercado monetario.<\/li>\n<li>Cuando los prestamistas tienen pocos fondos para prestar, a menudo recaudan dinero a trav\u00e9s de promociones de Certificados. En consecuencia, es posible que pueda obtener una tasa mucho m\u00e1s alta que los rendimientos actuales del mercado a trav\u00e9s de incentivos de bonificaci\u00f3n.<\/li>\n<\/ul>\n<h2>Desventajas de los certificados:<\/h2>\n<ul>\n<li>Su dinero est\u00e1 bloqueado durante su mandato. Si surgen otras oportunidades de inversi\u00f3n, las tasas de inter\u00e9s aumentan o necesita acceso a sus fondos, no podr\u00e1 retirar el dinero sin incurrir en una tarifa o multa.<\/li>\n<li>La inflaci\u00f3n hace que las tasas de inter\u00e9s suban. Si su dinero est\u00e1 encerrado en un certificado a largo plazo, podr\u00eda perder las crecientes tasas de inter\u00e9s.<\/li>\n<\/ul>\n<h2>Maneras inteligentes de utilizar los certificados:<\/h2>\n<p>Los certificados son cuentas de inversi\u00f3n vers\u00e1tiles que pueden generar un buen rendimiento sin riesgo. Si bien los dividendos m\u00e1s altos son buenos, es el hecho de que su dinero est\u00e1 bloqueado lo que ayuda a tantos miembros. Al verse obligado a ahorrar, es m\u00e1s probable que logre sus objetivos financieros.<\/p>\n<p>A continuaci\u00f3n se presentan varias estrategias para utilizar los certificados a su favor:<\/p>\n<ul>\n<li><strong>Diversificar las inversiones:<\/strong>\u00a0Una cartera de inversiones bien diversificada es una estrategia ganadora para cualquier inversor. Agregar certificados a su cartera durante un entorno de tasas en alza generar\u00e1 fuertes dividendos sin el riesgo de mercado.<\/li>\n<li><strong>Inversiones conservadoras:<\/strong>\u00a0Si est\u00e1 a punto de jubilarse, podr\u00eda ser el momento de reducir su tolerancia al riesgo y adoptar un enfoque de inversi\u00f3n m\u00e1s conservador. Los certificados producir\u00e1n dividendos favorables sin riesgos de mercado innecesarios.<\/li>\n<li><strong>Inversiones por primera vez:<\/strong>\u00a0Los certificados son un excelente primer paso si est\u00e1 listo para comenzar a invertir pero todav\u00eda no tiene el valor para posibles p\u00e9rdidas en el mercado. Te ense\u00f1an a no tocar tu dinero durante per\u00edodos prolongados y a dejarlo crecer mediante inter\u00e9s compuesto.<\/li>\n<li><strong>Metas financieras de rango medio (de 1 a 5 a\u00f1os):<\/strong>\u00a0Debido a que sus fondos est\u00e1n bloqueados, los Certificados son la manera perfecta de ahorrar para metas financieras futuras, tales como:\n<ul>\n<li>Un pago inicial o costos de cierre de una casa nueva.<\/li>\n<li>Un fondo universitario para su hijo.<\/li>\n<li>Unas vacaciones de ensue\u00f1o para tu familia.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2>\u00a1Estamos aqu\u00ed para ayudar!<\/h2>\n<p>Si bien nadie disfruta de per\u00edodos de alta inflaci\u00f3n, en todo hay oportunidades. En este momento, los rendimientos est\u00e1n subiendo y los certificados est\u00e1n regresando con fuerza. Estas cuentas populares podr\u00edan ser la herramienta perfecta para ayudarle a aumentar el rendimiento de su inversi\u00f3n sin riesgos adicionales.<\/p>\n<p>Si desea obtener m\u00e1s informaci\u00f3n sobre los certificados o est\u00e1 listo para abrir una cuenta, estamos aqu\u00ed para ayudarlo. Visite cualquiera de nuestras diez sucursales convenientes o llame al 888-777-9982 para hablar con un miembro del equipo hoy.<\/p>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Esta cooperativa de cr\u00e9dito est\u00e1 asegurada a nivel federal por la Administraci\u00f3n Nacional de Cooperativas de Cr\u00e9dito.<\/p>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Prestamista de vivienda equitativa<\/p>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de un a\u00f1o de precios en alza, los miembros todav\u00eda est\u00e1n lidiando con los efectos del aumento de la inflaci\u00f3n. Si a eso le sumamos el desempe\u00f1o inestable de Wall Street, la gente busca un lado positivo. Una de esas oportunidades est\u00e1 empezando a brillar a medida que las tasas de ahorro tambi\u00e9n empiezan a subir: se llama Certificado de Acciones. <a href=\"https:\/\/www.patriotfcu.org\/es\/blog\/why-are-certificates-becoming-so-popular\/\">sigue leyendo <span class=\"meta-nav\">\u2192<\/span><\/a><\/p>","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-3586","post","type-post","status-publish","format-standard","hentry","category-personal-finance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Why are Certificates Becoming So Popular? - Patriot Federal Credit Union<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patriotfcu.org\/es\/blog\/por-que-los-certificados-se-estan-volviendo-tan-populares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Why are Certificates Becoming So Popular? - Patriot Federal Credit Union\" \/>\n<meta property=\"og:description\" content=\"After a year of surging prices, members are still grappling with the effects of rising inflation. Add in the rocky performance of Wall Street, and people are looking for a silver lining. One such opportunity is beginning to shine as savings rates also start to climb \u2013 it\u2019s called a Share Certificate. Continue reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patriotfcu.org\/es\/blog\/por-que-los-certificados-se-estan-volviendo-tan-populares\/\" \/>\n<meta property=\"og:site_name\" content=\"Patriot Federal Credit Union\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-25T04:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T15:54:54+00:00\" \/>\n<meta name=\"author\" content=\"Ken Ditzler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Ditzler\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/\"},\"author\":{\"name\":\"Ken Ditzler\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#\\\/schema\\\/person\\\/64f7330195a0ff0acbd56677fe8baab3\"},\"headline\":\"Why are Certificates Becoming So Popular?\",\"datePublished\":\"2023-04-25T04:15:00+00:00\",\"dateModified\":\"2024-05-02T15:54:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/\"},\"wordCount\":6,\"articleSection\":[\"Personal Finance\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/\",\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/\",\"name\":\"Why are Certificates Becoming So Popular? - Patriot Federal Credit Union\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#website\"},\"datePublished\":\"2023-04-25T04:15:00+00:00\",\"dateModified\":\"2024-05-02T15:54:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#\\\/schema\\\/person\\\/64f7330195a0ff0acbd56677fe8baab3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/blog\\\/why-are-certificates-becoming-so-popular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patriotfcu.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Why are Certificates Becoming So Popular?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#website\",\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/\",\"name\":\"Patriot Federal Credit Union\",\"description\":\"Financial Services That Meet Your Need\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patriotfcu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.patriotfcu.org\\\/#\\\/schema\\\/person\\\/64f7330195a0ff0acbd56677fe8baab3\",\"name\":\"Ken Ditzler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g\",\"caption\":\"Ken Ditzler\"},\"url\":\"https:\\\/\\\/www.patriotfcu.org\\\/es\\\/blog\\\/author\\\/kditzler\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 los certificados se est\u00e1n volviendo tan populares? - Cooperativa de cr\u00e9dito federal Patriota","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patriotfcu.org\/es\/blog\/por-que-los-certificados-se-estan-volviendo-tan-populares\/","og_locale":"es_ES","og_type":"article","og_title":"Why are Certificates Becoming So Popular? - Patriot Federal Credit Union","og_description":"After a year of surging prices, members are still grappling with the effects of rising inflation. Add in the rocky performance of Wall Street, and people are looking for a silver lining. One such opportunity is beginning to shine as savings rates also start to climb \u2013 it\u2019s called a Share Certificate. Continue reading &rarr;","og_url":"https:\/\/www.patriotfcu.org\/es\/blog\/por-que-los-certificados-se-estan-volviendo-tan-populares\/","og_site_name":"Patriot Federal Credit Union","article_published_time":"2023-04-25T04:15:00+00:00","article_modified_time":"2024-05-02T15:54:54+00:00","author":"Ken Ditzler","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ken Ditzler"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/#article","isPartOf":{"@id":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/"},"author":{"name":"Ken Ditzler","@id":"https:\/\/www.patriotfcu.org\/#\/schema\/person\/64f7330195a0ff0acbd56677fe8baab3"},"headline":"Why are Certificates Becoming So Popular?","datePublished":"2023-04-25T04:15:00+00:00","dateModified":"2024-05-02T15:54:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/"},"wordCount":6,"articleSection":["Personal Finance"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/","url":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/","name":"\u00bfPor qu\u00e9 los certificados se est\u00e1n volviendo tan populares? - Cooperativa de cr\u00e9dito federal Patriota","isPartOf":{"@id":"https:\/\/www.patriotfcu.org\/#website"},"datePublished":"2023-04-25T04:15:00+00:00","dateModified":"2024-05-02T15:54:54+00:00","author":{"@id":"https:\/\/www.patriotfcu.org\/#\/schema\/person\/64f7330195a0ff0acbd56677fe8baab3"},"breadcrumb":{"@id":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patriotfcu.org\/blog\/why-are-certificates-becoming-so-popular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patriotfcu.org\/"},{"@type":"ListItem","position":2,"name":"Why are Certificates Becoming So Popular?"}]},{"@type":"WebSite","@id":"https:\/\/www.patriotfcu.org\/#website","url":"https:\/\/www.patriotfcu.org\/","name":"Patriot Federal Credit Union","description":"Servicios financieros que satisfacen sus necesidades","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patriotfcu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.patriotfcu.org\/#\/schema\/person\/64f7330195a0ff0acbd56677fe8baab3","name":"Ken Ditzler","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcb7149034ac6de6f2f8e3f9837ebe841daec60e4024d07bc8036783724e99d8?s=96&d=mm&r=g","caption":"Ken Ditzler"},"url":"https:\/\/www.patriotfcu.org\/es\/blog\/author\/kditzler\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/posts\/3586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/comments?post=3586"}],"version-history":[{"count":0,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/posts\/3586\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/media?parent=3586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/categories?post=3586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patriotfcu.org\/es\/wp-json\/wp\/v2\/tags?post=3586"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}